{"id":95757,"date":"2022-10-29T09:08:04","date_gmt":"2022-10-29T12:08:04","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/29\/prefeitos-do-nortao-firmam-parceria-com-sindusmad-para-fortalecer-setor-madeireiro\/"},"modified":"2022-10-29T09:08:04","modified_gmt":"2022-10-29T12:08:04","slug":"prefeitos-do-nortao-firmam-parceria-com-sindusmad-para-fortalecer-setor-madeireiro","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/29\/prefeitos-do-nortao-firmam-parceria-com-sindusmad-para-fortalecer-setor-madeireiro\/","title":{"rendered":"Prefeitos do Nort\u00e3o firmam parceria com Sindusmad para fortalecer setor madeireiro"},"content":{"rendered":"<p>Diretores do Sindicato das Ind\u00fastrias Madeireiras do Norte (Sindusmad) se reuniram, com industriais madeireiros em Ita\u00faba (100 km de Sinop) na \u00faltima reuni\u00e3o itinerante do ano. O prefeito Ant\u00f4nio Ferreira de Oliveira Neto (Toninho) defendeu o fortalecimento do setor de base florestal e uma das primeiras medidas \u00e9 a parceria firmada com o sindicato para trazer cursos de qualifica\u00e7\u00e3o profissional. \u201cA nossa economia \u00e9 oriunda do setor madeireiro. \u00c9 o que mais emprega e gera renda. Essas reuni\u00f5es contribuem para o desenvolvimento do setor na regi\u00e3o. Na pauta foi apresentado os cursos dispon\u00edveis e o munic\u00edpio vai fazer parceria com o Sindusmad para promover mais cursos. Ita\u00faba possui uma reserva florestal muito grande em manejo e precisamos desperdi\u00e7ar cada vez menos mat\u00e9ria prima e valorizar ainda mais os nossos produtos\u201d, disse.<\/p>\n<p>O prefeito do munic\u00edpio de Nova Santa Helena, Paulinho Bortolini, que tamb\u00e9m \u00e9 madeireiro e associado do Sindusmad, disse que os diretores apresentaram, na reuni\u00e3o itinerante, \u201cuma vis\u00e3o muito aberta para o futuro. O setor madeireiro sempre caminhou sozinho e o sindicato trouxe a associa\u00e7\u00e3o para unificar, compartilhar as experi\u00eancias porque o que d\u00e1 certo para um, leva para os demais. Isso \u00e9 muito importante. A classe est\u00e1 unida atrav\u00e9s do Sindusmad\u201d. \u201cEst\u00e3o de parab\u00e9ns, temos que continuar com essas reuni\u00f5es para abrir esse leque de op\u00e7\u00f5es, trazendo melhorias e investimentos. destacou, atrav\u00e9s da assessoria.<\/p>\n<p>Para o presidente do Sindusmad Wilson Jos\u00e9 Volkweis, avaliou que al\u00e9m dos industriais os gestores p\u00fablicos quais \u201cest\u00e3o otimistas com o futuro do mercado e o setor de base florestal nestes munic\u00edpios \u00e9 o respons\u00e1vel pela economia e pela arrecada\u00e7\u00e3o\u201d, salientou,<\/p>\n<p>A diretoria ainda far\u00e1 encontros em Sorriso e Marcel\u00e2ndia. Entretanto, est\u00e1 previsto no planejamento da diretoria a continuidade desta iniciativa em munic\u00edpios que comp\u00f5em a base florestal do Sindusmad para 2023. \u201cEssa foi a \u00faltima reuni\u00e3o do ano, mas com certeza, no pr\u00f3ximo ano vamos dar seguimento com a previs\u00e3o de fazer 5 a 6 reuni\u00f5es. \u00c9 o momento que nos reunimos para falar de ideias, de mercados, demanda e das a\u00e7\u00f5es\u201d, concluiu o presidente.<\/p>\n<p>A assessoria informou que a assembleia geral ser\u00e1 dia 03 de dezembro, em Sinop.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diretores do Sindicato das Ind\u00fastrias Madeireiras do Norte (Sindusmad) se reuniram, com industriais madeireiros em<\/p>\n","protected":false},"author":0,"featured_media":95758,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-95757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=95757"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/95758"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=95757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=95757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=95757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}