{"id":95222,"date":"2022-10-25T14:08:19","date_gmt":"2022-10-25T17:08:19","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/25\/bh-e-prefeitos-lulistas-decretam-gratuidade-de-onibus-no-domingo-zema-e-contra\/"},"modified":"2022-10-25T14:08:19","modified_gmt":"2022-10-25T17:08:19","slug":"bh-e-prefeitos-lulistas-decretam-gratuidade-de-onibus-no-domingo-zema-e-contra","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/25\/bh-e-prefeitos-lulistas-decretam-gratuidade-de-onibus-no-domingo-zema-e-contra\/","title":{"rendered":"BH e prefeitos lulistas decretam gratuidade de \u00f4nibus no domingo; Zema \u00e9 contra"},"content":{"rendered":"<p>\u00a0(FOLHAPRESS) &#8211; A disputa de Luiz In\u00e1cio Lula da Silva (PT) e Jair Bolsonaro (PL) pelos votos de Minas Gerais chegou nesta segunda-feira (24) aos transportes p\u00fablicos.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Enquanto o prefeito de Belo Horizonte, o lulista Fuad Noman (PSD), assinava ato estabelecendo gratuidade no sistema de \u00f4nibus no domingo (30), dia do segundo turno, o governador Romeu Zema (Novo), bolsonarista, dizia \u00e0 Folha de S.Paulo ser contra o poder p\u00fablico tomar tal medida.<\/p>\n<p>O pano de fundo da disputa tem a ver com a absten\u00e7\u00e3o e a tentativa de ganho eleitoral dos dois lados com uma maior ou menor aus\u00eancia de eleitores na vota\u00e7\u00e3o.<\/p>\n<p>De acordo com as pesquisas eleitorais, Lula tem maiores \u00edndices de inten\u00e7\u00e3o de voto entre a popula\u00e7\u00e3o mais pobre, p\u00fablico-alvo das medidas de gratuidade no dia da elei\u00e7\u00e3o.<\/p>\n<p>&#8220;Votar \u00e9 direito de todos. E \u00e9 dever do Estado promover esfor\u00e7os para que esse direito seja garantido. Segundo decis\u00e3o do STF na ADPF 1013, a PBH [Prefeitura de Belo Horizonte] vai disponibilizar servi\u00e7o municipal de transporte p\u00fablico coletivo de \u00f4nibus de maneira gratuita no domingo (30). Bom voto a todos&#8221;, escreveu Fuad em suas redes sociais.<\/p>\n<p>A articula\u00e7\u00e3o pol\u00edtica para a concess\u00e3o da medida contou com a participa\u00e7\u00e3o de coordenadores da campanha de Lula em Minas, entre eles o senador Alexandre Silveira (PSD).<\/p>\n<p>Prefeituras e empresas concession\u00e1rias est\u00e3o autorizadas a oferecer transporte p\u00fablico de forma gratuita para a popula\u00e7\u00e3o no domingo. A decis\u00e3o \u00e9 do ministro Lu\u00eds Roberto Barroso, do Supremo Tribunal Federal (STF), que atendeu a um pedido de esclarecimento da Rede Sustentabilidade.<\/p>\n<p>Em entrevista \u00e0 Folha de S.Paulo, o governador Romeu Zema afirmou que prefeituras que no dia da elei\u00e7\u00e3o tomem medidas que fujam \u00e0 normalidade estar\u00e3o adotando uma atitude suspeita.<\/p>\n<p>&#8220;J\u00e1 expressei a minha opini\u00e3o. \u00c9 uma decis\u00e3o municipal, mas a nossa orienta\u00e7\u00e3o \u00e9 essa: que se trabalhe na v\u00e9spera e no dia da elei\u00e7\u00e3o como se trabalha o resto do ano. Se algu\u00e9m est\u00e1 trabalhando diferente, gera suspeita&#8221;, afirmou.<\/p>\n<p>Ele negou que esteja pressionando prefeitos a n\u00e3o dar gratuidade no transporte no dia da elei\u00e7\u00e3o.<\/p>\n<p>Zema se tornou um dos principais cabos-eleitorais de Bolsonaro neste segundo turno. Com ataques fortes a Lula e ao PT, ele tem prometido a aliados do presidente fazer a elei\u00e7\u00e3o virar no estado. No primeiro turno, Lula venceu em Minas com diferen\u00e7a de cinco pontos percentuais.<\/p>\n<p>&#8220;A not\u00edcia que eu tenho \u00e9 que ele [Zema] est\u00e1 pedindo aos prefeitos para n\u00e3o ajudar os eleitores a votar, isso \u00e9 um crime. O eleitor do distrito, da zona rural, de baixa renda, ele precisa da ajuda do poder p\u00fablico para poder exercer a sua cidadania&#8221;, afirmou Silveira.<\/p>\n<p>A batalha por votos no estado se tornou prioridade das duas campanhas por reunir o segundo maior eleitorado do pa\u00eds e pelo simbolismo de que desde a redemocratiza\u00e7\u00e3o todos os eleitos tamb\u00e9m triunfaram nas urnas mineiras.<\/p>\n<p>Al\u00e9m de Belo Horizonte, outras prefeituras j\u00e1 se posicionaram a favor da gratuidade do transporte p\u00fablico. \u00c9 o caso de Te\u00f3filo Otoni, cidade que j\u00e1 recebeu visitas de Lula e deve receber agenda de campanha de Bolsonaro nesta semana, e Ouro Preto, onde o prefeito tamb\u00e9m j\u00e1 declarou apoio a Lula.<\/p>\n<p>&#8220;Muitos n\u00e3o est\u00e3o indo votar por falta de dinheiro para n\u00e3o pagar a passagem, principalmente quem mora na zona rural, onde n\u00e3o tem transporte perene. Vamos conceder a gratuidade e j\u00e1 estamos informando a Justi\u00e7a eleitoral&#8221;, diz o prefeito de Te\u00f3filo Otoni, Daniel Sucupira (PT).<\/p>\n<p>Ele sugere que mais prefeitos viabilizem o transporte gratuito no domingo. &#8220;Isso \u00e9 muito importante para a democracia. No mapa das absten\u00e7\u00f5es, as maiores est\u00e3o aqui no Vale do Mucuri [regi\u00e3o onde fica o munic\u00edpio] e Jequitinhonha&#8221;, disse.<\/p>\n<p>J\u00e1 em Montes Claros, no norte de Minas, o prefeito Humberto Souto (Cidadania) diz que a gratuidade n\u00e3o est\u00e1 sob an\u00e1lise at\u00e9 o momento. &#8220;N\u00e3o temos esse h\u00e1bito. Aqui nunca teve, e n\u00e3o sei se nem temos dinheiro or\u00e7ament\u00e1rio para isso&#8221;, afirma Souto, que apoia Bolsonaro.<\/p>\n<p>Montes Claros foi palco de com\u00edcio do presidente da Rep\u00fablica ao lado de Zema, no dia 18.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/1958513\/bh-e-prefeitos-lulistas-decretam-gratuidade-de-onibus-no-domingo-zema-e-contra?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0(FOLHAPRESS) &#8211; A disputa de Luiz In\u00e1cio Lula da Silva (PT) e Jair Bolsonaro (PL)<\/p>\n","protected":false},"author":0,"featured_media":95223,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-95222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=95222"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/95223"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=95222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=95222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=95222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}