{"id":95206,"date":"2022-10-25T13:08:04","date_gmt":"2022-10-25T16:08:04","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/25\/tce-concede-cinco-dias-para-prefeitura-de-cuiaba-explicar-atraso-nos-repasses-para-hospital-de-cancer\/"},"modified":"2022-10-25T13:08:04","modified_gmt":"2022-10-25T16:08:04","slug":"tce-concede-cinco-dias-para-prefeitura-de-cuiaba-explicar-atraso-nos-repasses-para-hospital-de-cancer","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/25\/tce-concede-cinco-dias-para-prefeitura-de-cuiaba-explicar-atraso-nos-repasses-para-hospital-de-cancer\/","title":{"rendered":"TCE concede cinco dias para prefeitura de Cuiab\u00e1 explicar atraso nos repasses para Hospital de C\u00e2ncer"},"content":{"rendered":"<p>O Tribunal de Contas de Mato Grosso decidiu conceder prazo de cinco dias \u00fateis para que a prefeitura de Cuiab\u00e1 e a secretaria municipal de Sa\u00fade prestem informa\u00e7\u00f5es sobre o atraso nos repasses financeiros para o Hospital de C\u00e2ncer de Mato Grosso, na capital.<\/p>\n<p>A solicita\u00e7\u00e3o foi feita pelo supervisor do Comit\u00ea Tem\u00e1tico de Sa\u00fade, conselheiro Guilherme Antonio Maluf, por meio dos of\u00edcios\u00a0 encaminhados ontem e tamb\u00e9m questiona quais provid\u00eancias est\u00e3o sendo adotadas pela administra\u00e7\u00e3o municipal e, especialmente, se h\u00e1 uma proposta para a quita\u00e7\u00e3o dos d\u00e9bitos.<\/p>\n<p>\u201cRegistro que, dentre os objetivos do Comit\u00ea Tem\u00e1tico de Sa\u00fade deste Tribunal, est\u00e1 a promo\u00e7\u00e3o de a\u00e7\u00f5es em conjunto com os fiscalizados com o intuito de colaborar com a efetividade das pol\u00edticas p\u00fablicas da \u00e1rea da sa\u00fade\u201d, ressalta em trecho do documento.<\/p>\n<p>O valor do repasse que estaria atrasado n\u00e3o foi informado.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Contas de Mato Grosso decidiu conceder prazo de cinco dias \u00fateis para<\/p>\n","protected":false},"author":0,"featured_media":95207,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-95206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=95206"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/95207"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=95206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=95206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=95206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}