{"id":95017,"date":"2022-10-24T12:08:06","date_gmt":"2022-10-24T15:08:06","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/24\/prefeito-e-coronel-avaliam-area-para-construir-quartel-dos-bombeiros-em-colider\/"},"modified":"2022-10-24T12:08:06","modified_gmt":"2022-10-24T15:08:06","slug":"prefeito-e-coronel-avaliam-area-para-construir-quartel-dos-bombeiros-em-colider","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/24\/prefeito-e-coronel-avaliam-area-para-construir-quartel-dos-bombeiros-em-colider\/","title":{"rendered":"Prefeito e coronel avaliam \u00e1rea para construir quartel dos bombeiros em Col\u00edder"},"content":{"rendered":"<p>O prefeito Hemerson M\u00e1ximo est\u00e1 analisando, juntamente com o coronel Paulo Correia, a futura sede do Corpo de Bombeiros. A prov\u00e1vel \u00e1rea \u00e9 o quarteir\u00e3o ao lado da escola Antonio Paes de Barros, onde ambos estiveram, fazendo a an\u00e1lise t\u00e9cnica. A prefeitura articula par a secretaria estadual de Educa\u00e7\u00e3o ceder uma parte do terreno para construir o quartel.<\/p>\n<p>\u201cO projeto est\u00e1 bem encaminhado e sendo alinhado na secretaria estadual de Educa\u00e7\u00e3o. Acredito que em breve estaremos com a nova sede do Corpo de Bombeiros\u201d, disse Maninho. O montante investido n\u00e3o foi mencionado. O coronel Paulo destacou que essa realiza\u00e7\u00e3o s\u00f3 est\u00e1 sendo poss\u00edvel devido ao trabalho s\u00e9rio desenvolvido pela administra\u00e7\u00e3o municipal e o Corpo de Bombeiros tem sido parceiro nestes trabalhos.<\/p>\n<p>A sede atual da 12\u00aa Companhia Independente de Bombeiro Militar tem 1.880 m\u00b2. A corpora\u00e7\u00e3o est\u00e1 em Col\u00edder desde 2007 e atende ocorr\u00eancias em cidades da regi\u00e3o.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Hemerson M\u00e1ximo est\u00e1 analisando, juntamente com o coronel Paulo Correia, a futura sede<\/p>\n","protected":false},"author":0,"featured_media":95018,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-95017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=95017"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/95017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/95018"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=95017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=95017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=95017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}