{"id":94987,"date":"2022-10-24T09:08:07","date_gmt":"2022-10-24T12:08:07","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/24\/prefeitura-licita-pavimentacao-de-trevo-no-nortao-com-verba-estadual-obra-de-suma-importancia-diz-secretario\/"},"modified":"2022-10-24T09:08:07","modified_gmt":"2022-10-24T12:08:07","slug":"prefeitura-licita-pavimentacao-de-trevo-no-nortao-com-verba-estadual-obra-de-suma-importancia-diz-secretario","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/24\/prefeitura-licita-pavimentacao-de-trevo-no-nortao-com-verba-estadual-obra-de-suma-importancia-diz-secretario\/","title":{"rendered":"Prefeitura licita pavimenta\u00e7\u00e3o de trevo no Nort\u00e3o com verba estadual; \u201cobra de suma import\u00e2ncia\u201d, diz secret\u00e1rio"},"content":{"rendered":"<p>A prefeitura de Itanhang\u00e1 (208 quil\u00f4metros de Sinop) abriu procedimento licitat\u00f3rio para contratar a empresa que ir\u00e1 pavimentar o trevo do entroncamento entre as rodovias MTs 338 e 242. O valor de investimento \u00e9 de R$ 3,3 milh\u00f5es e ser\u00e1 repassado pelo governo do Estado, via secretaria estadual de Infraestrutura, conforme conv\u00eanio assinado com a prefeitura, em mar\u00e7o deste ano.<\/p>\n<p>Segundo Jeferson da Silva Santos, secret\u00e1rio municipal de Transportes, Obras, Servi\u00e7os P\u00fablicos e Saneamento, \u201ca obra \u00e9 de suma import\u00e2ncia para regulariza\u00e7\u00e3o das passagens de ve\u00edculos que adentram ao munic\u00edpio\u201d. Ele tamb\u00e9m destacou que a implanta\u00e7\u00e3o do trevo \u201c\u00e9 uma quest\u00e3o de ordem no tr\u00e2nsito e que sua constru\u00e7\u00e3o evitar\u00e1 acidentes entre os que ali transitam\u201d.<\/p>\n<p>O gestor ainda avaliou que a pavimenta\u00e7\u00e3o ainda ir\u00e1 reduzir a manuten\u00e7\u00e3o das vias urbanas pelo munic\u00edpio, \u201co que ir\u00e1 proporcionar economia\u201d, e que \u201ca cidade asfaltada melhora o aspecto visual, trazendo um ambiente agrad\u00e1vel e organizado, al\u00e9m do mais, em se tratando da entrada do munic\u00edpio\u201d.<\/p>\n<p>As propostas das empresas ser\u00e3o recebidas no dia 3 de novembro. A que vencer o procedimento licitat\u00f3rio ter\u00e1 150 dias para concluir as obras, que abrangem um trecho de 392 metros.<\/p>\n<p>Em Itanhang\u00e1, conforme S\u00f3 Not\u00edcias j\u00e1 informou, o governo do Estado tamb\u00e9m investir\u00e1 recursos na amplia\u00e7\u00e3o da escola estadual Joaquim Barbosa, localizada na rua Nossa Senhora Aparecida. Al\u00e9m de novas salas de aulas, ser\u00e1 constru\u00edda uma quadra poliesportiva e instalado um posto de transforma\u00e7\u00e3o.<\/p>\n<p>Ser\u00e3o constru\u00eddas oito novas salas de aula, com espa\u00e7o total de 624 metros quadrados. J\u00e1 a quadra poliesportiva ter\u00e1 670 metros quadrados. O valor do investimento \u00e9 de R$ 2,7 milh\u00f5es e ser\u00e1 repassado pela secretaria estadual de Educa\u00e7\u00e3o (Seduc).<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prefeitura de Itanhang\u00e1 (208 quil\u00f4metros de Sinop) abriu procedimento licitat\u00f3rio para contratar a empresa<\/p>\n","protected":false},"author":0,"featured_media":94988,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-94987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94987"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/94988"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}