{"id":94867,"date":"2022-10-23T12:08:17","date_gmt":"2022-10-23T15:08:17","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/23\/morre-luiz-galvao-poeta-e-fundador-dos-novos-baianos-aos-87-anos\/"},"modified":"2022-10-23T12:08:17","modified_gmt":"2022-10-23T15:08:17","slug":"morre-luiz-galvao-poeta-e-fundador-dos-novos-baianos-aos-87-anos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/23\/morre-luiz-galvao-poeta-e-fundador-dos-novos-baianos-aos-87-anos\/","title":{"rendered":"Morre Luiz Galv\u00e3o, poeta e fundador dos Novos Baianos, aos 87 anos"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Poeta e fundador dos Novos Baianos, Luiz Galv\u00e3o morreu na noite deste s\u00e1bado (22), aos 87 anos. Ele estava internado no InCor (Instituto do Cora\u00e7\u00e3o do Hospital das Cl\u00ednicas da Faculdade de Medicina da USP), em S\u00e3o Paulo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A morte de Luiz Galv\u00e3o, cuja causa n\u00e3o foi divulgada, foi confirmada por seu filho, Lahir\u00ed Galv\u00e3o, e por Caetano Veloso, al\u00e9m da companheira de banda Baby do Brasil, todos no Instagram. &#8220;V\u00e1 em paz, meu papai!&#8221;, escreveu o filho.<\/p>\n<p>Baby do Brasil afirmou que nos \u00faltimos anos ele enfrentou diversos problemas de sa\u00fade, e tamb\u00e9m escreveu sobre sua rela\u00e7\u00e3o com o artista. &#8220;Vivemos tantos anos juntos, em grupo, morando no s\u00edtio Cantinho do Vov\u00f4, na Cobertura de Botafogo e, em outros endere\u00e7os. Totalizamos dez anos de vida juntos. Tivemos esse privil\u00e9gio, de estarmos sob o mesmo teto, vivendo uma experi\u00eancia \u00fanica e intransfer\u00edvel.&#8221;<\/p>\n<p>Ela se lembrou de m\u00fasicas que ele escreveu para que ela cantasse, como &#8220;A Menina Dan\u00e7a&#8221; e &#8220;Tinindo e Trincando&#8221;, duas das mais conhecidas na voz da cantora. &#8220;Nos tornamos uma fam\u00edlia, desde 1969, quando come\u00e7amos. Investimos com extrema dedica\u00e7\u00e3o no prop\u00f3sito de fazermos uma m\u00fasica, genu\u00edna, com as melhores influ\u00eancias de todos e, de todos os tempos e sobretudo brasileir\u00edssima!&#8221;<\/p>\n<p>Caetano Veloso, que comp\u00f4s com Galv\u00e3o a m\u00fasica &#8220;O Farol da Barra&#8221;, tamb\u00e9m se despediu do amigo. &#8220;Galv\u00e3o criou e liderou o grupo Novos Baianos, acontecimento que se coloca entre os que mudaram o rumo da hist\u00f3ria do Brasil. Sendo de Juazeiro, atraiu Jo\u00e3o Gilberto para a casa coletiva em que viviam os membros do grupo. E isso definiu o caminho rico que se pode resumir no \u00e1lbum Acabou Chorare mas que se desdobrou em muito mais. Vamos sentir saudade dele &#8211; e tamb\u00e9m celebrar a peculiaridade de sua pessoa.&#8221;<\/p>\n<p>Nascido em Juazeiro, na Bahia, Luiz Galv\u00e3o se juntou em 1969 aos amigos Moraes Moreira e Paulinho Boca de Cantor para formar os Novos Baianos, um dos grupos mais importantes e criativos da m\u00fasica brasileira. Eles depois incorporaram Pepeu Gomes e Baby do Brasil.<\/p>\n<p>Galv\u00e3o foi autor das letras da maioria das m\u00fasicas gravadas pela banda, entre elas cl\u00e1ssicos como &#8220;Preta Pretinha&#8221;, &#8220;Mist\u00e9rio do Planeta&#8221; e &#8220;Acabou Chorare&#8221;, estas musicadas pelo parceiro Moraes Moreira.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/1957875\/morre-luiz-galvao-poeta-e-fundador-dos-novos-baianos-aos-87-anos?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Poeta e fundador dos Novos Baianos, Luiz Galv\u00e3o morreu na<\/p>\n","protected":false},"author":0,"featured_media":94868,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-94867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94867"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/94868"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}