{"id":94787,"date":"2022-10-21T19:08:13","date_gmt":"2022-10-21T22:08:13","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/21\/clippers-derrubam-lakers-em-1o-classico-da-temporada-da-nba-bucks-vencem\/"},"modified":"2022-10-21T19:08:13","modified_gmt":"2022-10-21T22:08:13","slug":"clippers-derrubam-lakers-em-1o-classico-da-temporada-da-nba-bucks-vencem","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/21\/clippers-derrubam-lakers-em-1o-classico-da-temporada-da-nba-bucks-vencem\/","title":{"rendered":"Clippers derrubam Lakers em 1\u00ba cl\u00e1ssico da temporada da NBA; Bucks vencem"},"content":{"rendered":"<p>No primeiro cl\u00e1ssico da nova temporada da NBA, o Los Angeles Clippers derrubou o Los Angeles Lakers, do astro LeBron James, por 103 a 97, na madrugada desta sexta-feira. O duelo, com mando dos Lakers, marcou o retorno de Kawhi Leonard, baixa dos Clippers ao longo de toda a temporada passada. Em outro jogo da noite, o Milwaukee Bucks bateu o Philadelphia 76ers por 90 a 88.  <\/p>\n<p>Ap\u00f3s mais de um ano, os Clippers puderam contar com Kawhi Leonard, que sofreu uma ruptura de ligamento no joelho direito em junho de 2021 e n\u00e3o pisou em quadra na temporada passada. Nesta madrugada, come\u00e7ou no banco de reservas e jogou por 21 minutos. Foi o suficiente para anotar 14 pontos, sete rebotes e duas assist\u00eancias.<\/p>\n<\/p>\n<p>Coadjuvante, ele viu os Clippers dominarem com seu jogo coletivo. Outros cinco jogadores da equipe chegaram aos dois d\u00edgitos em pontua\u00e7\u00e3o. Paul George e Ivica Zubac foram os maiores destaques, com um &#8220;double-double&#8221; cada. George registrou 15 pontos e 10 rebotes, enquanto Zubac marcou 14 pontos e obteve 17 rebotes. John Wall e Marcus Morris  contribu\u00edram com 15 e 14 pontos, respectivamente. <\/p>\n<\/p>\n<p>Pelos Lakers, o trio formado por LeBron, Lonnie Walker IV e Anthony Davis comandou o time. O astro obteve um &#8220;double-double&#8221; de 20 pontos e 10 rebotes. Walker foi o cestinha da partida, com 26 pontos. E Davis anotou 25 pontos e oito rebotes. <\/p>\n<\/p>\n<p>A partida marcou a estreia dos Clippers na temporada, enquanto os Lakers jogaram pela segunda vez. Na estreia, tamb\u00e9m foram derrotados, pelo Golden State Warriors. <\/p>\n<\/p>\n<p>No outro jogo da noite, o Milwaukee Bucks estreou com vit\u00f3ria apertada sobre o Philadelphia 76ers por 90 a 88, em duelo decidido nos segundos finais, na Filad\u00e9lfia. Em noite inspirada, James Harden foi o cestinha do confronto, com 31 pontos (al\u00e9m de anotar nove assist\u00eancias e oito rebotes), mas n\u00e3o conseguiu evitar nova derrota dos Sixers, que j\u00e1 haviam sido batidos na estreia.<\/p>\n<\/p>\n<p>O esfor\u00e7o de Harden, em conjunto com as atua\u00e7\u00f5es medianas de Joel Embiid e Tyrese Maxey (ambos com 15 pontos), n\u00e3o foram suficientes para parar o j\u00e1 embalado Giannis Antetokounmpo, novamente candidato a MVP da temporada. O grego esteve perto de abrir sua temporada com um &#8220;triple-double&#8221;. Foram 21 pontos, 13 rebotes e oito assist\u00eancias. O astro dos Bucks contou ainda com o apoio de Brook Lopez e Grayson Allen, com 17 e 12 pontos, respectivamente. <\/p>\n<\/p>\n<p><b>Acompanhe os jogos da noite desta sexta-feira:<\/b> <\/p>\n<\/p>\n<p>Washington Wizards x Chicago Bulls<\/p>\n<p>Charlotte Hornets x New Orleans Pelicans <\/p>\n<p>Indiana Pacers x San Antonio Spurs<\/p>\n<p>Miami Heat x Boston Celtics<\/p>\n<p>New York Knicks x Detroit Pistons<\/p>\n<p>Atlanta Hawks x Orlando Magic<\/p>\n<p>Brooklyn Nets x Toronto Raptors<\/p>\n<p>Houston Rockets x Memphis Grizzlies<\/p>\n<p>Minnesota Timberwolves x Utah Jazz<\/p>\n<p>Golden State Warriors x Denver Nuggets<\/p>\n<p>Portland Trail Blazers x Phoenix Suns<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1957320\/clippers-derrubam-lakers-em-1-classico-da-temporada-da-nba-bucks-vencem?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No primeiro cl\u00e1ssico da nova temporada da NBA, o Los Angeles Clippers derrubou o Los<\/p>\n","protected":false},"author":0,"featured_media":94788,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-94787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94787"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/94788"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}