{"id":94761,"date":"2022-10-21T13:08:21","date_gmt":"2022-10-21T16:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/21\/nova-frente-fria-provoca-chuva-e-ventania-em-sao-paulo-a-partir-desta-sexta-feira\/"},"modified":"2022-10-21T13:08:21","modified_gmt":"2022-10-21T16:08:21","slug":"nova-frente-fria-provoca-chuva-e-ventania-em-sao-paulo-a-partir-desta-sexta-feira","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/21\/nova-frente-fria-provoca-chuva-e-ventania-em-sao-paulo-a-partir-desta-sexta-feira\/","title":{"rendered":"Nova frente fria provoca chuva e ventania em S\u00e3o Paulo a partir desta sexta-feira"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; A combina\u00e7\u00e3o de uma nova frente fria e a\u00e7\u00e3o do calor e umidade t\u00edpicos da primavera deve provocar chuvas fortes e ventania em todo o estado de S\u00e3o Paulo a partir desta sexta-feira (21), de acordo com o Inmet (Instituto Nacional de Meteorologia).<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A Defesa Civil do Estado de S\u00e3o Paulo emitiu um alerta para o per\u00edodo, que tende a permanecer at\u00e9 s\u00e1bado (22). O \u00f3rg\u00e3o informa que n\u00e3o h\u00e1 previs\u00e3o de grandes acumulados de chuva, ficando por volta dos 50 mililitros.<\/p>\n<p>&#8220;Por\u00e9m, como um grande volume de \u00e1gua pode cair em um espa\u00e7o curto de tempo, pode trazer alguns transtornos, como deslizamentos, desabamentos, alagamentos, enchentes e destelhamentos&#8221;, afirma o comunicado.<\/p>\n<p>H\u00e1 previs\u00e3o de ventos que variam de 50 a 80 km\/h em todo o estado. Na Grande S\u00e3o Paulo, eles devem chegar a 70 km\/h, segundo a Defesa Civil.<\/p>\n<p>O meteorologista Olivio Bahia, do Inmet, diz que \u00e1reas de instabilidade relacionadas ao calor e \u00e0 umidade j\u00e1 est\u00e3o afetando a regi\u00e3o Sul. Na \u00faltima quarta (19), por exemplo, foi registrada queda de granizo em cidades do oeste de Santa Catarina.<\/p>\n<p>Hoje [20], no final da noite, uma frente fria se forma sobre o Rio Grande do Sul e vai para o oceano Atl\u00e2ntico, &#8216;beliscando&#8217; \u00e1reas do Sul e de S\u00e3o Paulo. \u00c9 o que a gente chama de linha frontal. Ela vai ficar alinhando a umidade entre o oceano e Amaz\u00f4nia, formando um canal. Todo esse processo deve causar chuva&#8221;, explica Bahia.<\/p>\n<p>Essa frente fria \u00e9 originada por um ciclone extratropical, respons\u00e1vel pelos ventos fortes e poss\u00edvel queda de granizo, segundo o Inmet.<\/p>\n<p>A previs\u00e3o \u00e9 que esse sistema fique estacionado sobre S\u00e3o Paulo at\u00e9 este s\u00e1bado (22), quando a chuva tende a dar uma tr\u00e9gua nos estados do Sul.<\/p>\n<p>A partir de domingo (23), ele deve se deslocar para o norte, levando as chuvas fortes para Minas Gerais, Rio de Janeiro e Esp\u00edrito Santo at\u00e9 o in\u00edcio da pr\u00f3xima semana.<\/p>\n<p>&#8220;O impacto dessa frente na temperatura n\u00e3o ser\u00e1 t\u00e3o expressivo. Ela vai atuar mais pelo oceano, ajudando a organizar o canal de umidade&#8221;, finaliza o meteorologista.<\/p>\n<p>O CGE (Centro de Gerenciamento de Emerg\u00eancias Clim\u00e1ticas) da Prefeitura de S\u00e3o Paulo prev\u00ea temperaturas m\u00ednimas de 18\u00b0 e 16\u00b0 para sexta e s\u00e1bado, respectivamente, e m\u00e1ximas de 24\u00b0 e 20\u00b0.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/1957332\/nova-frente-fria-provoca-chuva-e-ventania-em-sao-paulo-a-partir-desta-sexta-feira?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; A combina\u00e7\u00e3o de uma nova frente fria e a\u00e7\u00e3o do calor e umidade<\/p>\n","protected":false},"author":0,"featured_media":94762,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-94761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94761"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/94762"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}