{"id":94685,"date":"2022-10-20T18:08:10","date_gmt":"2022-10-20T21:08:10","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/20\/dois-professores-sao-candidatos-a-diretor-campus-da-unemat-sinop\/"},"modified":"2022-10-20T18:08:10","modified_gmt":"2022-10-20T21:08:10","slug":"dois-professores-sao-candidatos-a-diretor-campus-da-unemat-sinop","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/20\/dois-professores-sao-candidatos-a-diretor-campus-da-unemat-sinop\/","title":{"rendered":"Dois professores s\u00e3o candidatos a diretor c\u00e2mpus da Unemat Sinop"},"content":{"rendered":"<p>Dois professores v\u00e3o concorrer a elei\u00e7\u00e3o de diretor pol\u00edtico pedag\u00f3gico-financeiro do c\u00e2mpus de Sinop da Universidade Estadual de Mato Grosso. \u00c2ngela Ester Mallmann Centenaro e J\u00falio Cesar Beltrame Benatti tiveram inscri\u00e7\u00f5es de suas candidaturas \u00a0deferidas. A campanha eleitoral ser\u00e1 realizada a partir da pr\u00f3xima ter\u00e7a (25), at\u00e9 9 de novembro, a elei\u00e7\u00e3o ser\u00e1 no dia 10, das 9h \u00e0s 21h.<\/p>\n<p>\u00c2ngela \u00e9 a primeira candidata mulher a diretoria do campus. Natural de Gramado, ela tem 52 anos e \u00e9 professora na Unemat desde 2005, onde leciona no curso de Ci\u00eancias Econ\u00f4micas. Doutora em Ci\u00eancias Sociais pela Universidade do Vale do Rio dos Sinos, no Rio Grande do Sul, e mestra em ci\u00eancias Sociais pela mesma universidade, sua primeira gradua\u00e7\u00e3o foi em Ci\u00eancias Econ\u00f4micas.<\/p>\n<p>\u201cA gente tem um n\u00facleo de pessoas que j\u00e1 fizeram hist\u00f3ria dentro da Unemat, fui diretora da Faculdade de Ci\u00eancias Sociais Aplicadas, s\u00f3 que acima disso n\u00e3o tive nenhum cargo. Essas pessoas que est\u00e3o comigo j\u00e1 conhecem muito bem a universidade, j\u00e1 trabalharam muito tanto aqui em Sinop quanto em C\u00e1ceres\u201d, disse, ao S\u00f3 Not\u00edcias.<\/p>\n<p>Quanto as necessidades do campus, \u00c2ngela descreveu que \u201ctem muitas demandas dentro da universidade, a gente sabe que n\u00e3o \u00e9 nada f\u00e1cil, mas a gente quer fazer com que o ambiente seja melhor para todos, para que possa crescer como universidade dentro da ci\u00eancia\u201d, analisou.<\/p>\n<p>O professor J\u00falio Cesar Beltrame, de 37 anos, \u00e9 doutor em Engenharia Civil pela Universidade Estadual de Campinas (Unicamp), onde tamb\u00e9m fez o mestrado e a primeira gradua\u00e7\u00e3o na mesma \u00e1rea. Natural de Bariri, S\u00e3o Paulo, veio para Sinop em 2014, ap\u00f3s ser aprovado no concurso para lecionar no curso de Engenharia Civil da Unemat, vinculado a Faculdade de Ci\u00eancias Exatas e Tecnol\u00f3gicas.<\/p>\n<p>Quanto as suas propostas o docente informou que pretende trabalhar para expandir a visibilidade do campus e as rela\u00e7\u00f5es pol\u00edticas com institui\u00e7\u00f5es externas, al\u00e9m de buscar solu\u00e7\u00f5es para alguns problemas que est\u00e3o se tornando recorrentes. A inten\u00e7\u00e3o segundo ele \u00e9 \u201cconectar mais a institui\u00e7\u00e3o com a comunidade externa. A quest\u00e3o de vestibular e ingressos, a ideia \u00e9 focar bastante nisso, temos pouca demanda nos vestibulares e editais de ingressos, e a pol\u00edtica de perman\u00eancia tamb\u00e9m \u00e9 uma das quest\u00f5es que a gente vai priorizar para evitar evas\u00e3o\u201d, declarou.<\/p>\n<p>Conforme o S\u00f3 Not\u00edcias j\u00e1 informou, a elei\u00e7\u00f5es v\u00e3o ocorrer no terminal eletr\u00f4nico destinado pela Comiss\u00e3o Eleitoral, o resultado final ser\u00e1 publicado no dia 17 e a posse dos novos diretores ser\u00e1 realizada em C\u00e1ceres, em 13 de dezembro<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois professores v\u00e3o concorrer a elei\u00e7\u00e3o de diretor pol\u00edtico pedag\u00f3gico-financeiro do c\u00e2mpus de Sinop da<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-94685","post","type-post","status-publish","format-standard","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94685"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94685\/revisions"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}