{"id":94402,"date":"2022-10-18T15:26:10","date_gmt":"2022-10-18T18:26:10","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=94402"},"modified":"2022-10-18T15:26:11","modified_gmt":"2022-10-18T18:26:11","slug":"policia-militar-de-guaranta-do-norte-apreende-30-quilos-de-explosivos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/18\/policia-militar-de-guaranta-do-norte-apreende-30-quilos-de-explosivos\/","title":{"rendered":"Pol\u00edcia Militar de Guarant\u00e3 do Norte apreende 30 quilos de explosivos"},"content":{"rendered":"\n<p>Policiais militares da 13\u00ba Companhia Independente e do Batalh\u00e3o de Opera\u00e7\u00f5es Especiais (Bope) realizaram a apreens\u00e3o e destrui\u00e7\u00e3o de cerca de 30 quilos de artefatos explosivos, na tarde desta segunda-feira (17\/10), em Guarant\u00e3 do Norte\/MT. O material foi localizado na noite anterior, na zona rural do munic\u00edpio.<\/p>\n\n\n\n<p>Conforme o boletim de ocorr\u00eancia, por volta de 22h de domingo (16)&nbsp;a equipe da PM recebeu den\u00fancias de moradores de uma comunidade rural&nbsp;sobre o encontro de um material semelhante a explosivos, na beira de uma rodovia.<\/p>\n\n\n\n<p>De imediato, os policiais militares foram at\u00e9 o local informado e confirmaram a veracidade do material.<\/p>\n\n\n\n<p>Em seguida, foi realizado contato com os policiais militares do Bope, que, por meio dos t\u00e9cnicos explosivistas do Batalh\u00e3o, repassaram orienta\u00e7\u00f5es a respeito dos procedimentos de seguran\u00e7a a serem adotados para o recolhimento e isolamento do material.<\/p>\n\n\n\n<p>Diante da situa\u00e7\u00e3o, a equipe da 13\u00ba CIPM realizou o registro de ocorr\u00eancia relatando a apreens\u00e3o do material.<\/p>\n\n\n\n<p>No dia seguinte, a equipe dos t\u00e9cnicos explosivistas do Bope se deslocou para a regi\u00e3o, com apoio do Centro Integrado de Opera\u00e7\u00f5es A\u00e9reas (Ciopaer), e realizou avalia\u00e7\u00e3o e relat\u00f3rio t\u00e9cnico do material, bem como a\u00a0destrui\u00e7\u00e3o dos artefatos explosivos, em um ambiente seguro.<\/p>\n\n\n\n<p><strong>Disque-den\u00fancia&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p>A sociedade pode contribuir com as a\u00e7\u00f5es da Pol\u00edcia Militar de qualquer cidade do Estado, sem precisar se identificar, por meio do 190, ou disque-den\u00fancia 0800.065.3939.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/www.pm.mt.gov.br\/documents\/2459523\/22793279\/Pol%C3%ADcia+Militar+apreende+30+quilos+de+explosivos+em+Guarant%C3%A3+do+Norte+2\/a6ae99ac-55c9-e25d-5b8b-ae5b0e34d3df?t=1666098473145+&amp;imageThumbnail=3\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong><em><span class=\"has-inline-color has-vivid-cyan-blue-color\">Da Assessoria da PM\/MT<\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais militares da 13\u00ba Companhia Independente e do Batalh\u00e3o de Opera\u00e7\u00f5es Especiais (Bope) realizaram a<\/p>\n","protected":false},"author":2,"featured_media":94403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-94402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94402"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94402\/revisions"}],"predecessor-version":[{"id":94404,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94402\/revisions\/94404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/94403"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}