{"id":94226,"date":"2022-10-17T09:08:28","date_gmt":"2022-10-17T12:08:28","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/17\/brasil-quer-ilan-goldfajn-ex-presidente-do-bc-no-comando-do-bid\/"},"modified":"2022-10-17T09:08:28","modified_gmt":"2022-10-17T12:08:28","slug":"brasil-quer-ilan-goldfajn-ex-presidente-do-bc-no-comando-do-bid","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/17\/brasil-quer-ilan-goldfajn-ex-presidente-do-bc-no-comando-do-bid\/","title":{"rendered":"Brasil quer Ilan Goldfajn, ex-presidente do BC, no comando do BID"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; O governo brasileiro quer emplacar na presid\u00eancia do BID (Banco Interamericano de Desenvolvimento) Ilan Goldfajn, ex-presidente do Banco Central e hoje diretor de Hemisf\u00e9rio Ocidental no FMI (Fundo Monet\u00e1rio Internacional).<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O ministro da Economia, Paulo Guedes, apresentou o nome de Goldfajn \u00e0 secret\u00e1ria do Tesouro dos EUA, Janet Yellen, na sexta-feira (14), segundo fontes em Washington, o qual teria sido recebido de forma positiva.<\/p>\n<p>Guedes foi \u00e0 capital americana participar dos encontros anuais do FMI e do Banco Mundial, e aproveitou a viagem para tentar angariar apoio a um nome brasileiro na chefia do BID \u2013ele tratou do assunto tamb\u00e9m com os ministros das finan\u00e7as do Chile, da Argentina e da Col\u00f4mbia.<\/p>\n<p>Se aprovado, Goldfajn ser\u00e1 o primeiro brasileiro no comando da institui\u00e7\u00e3o, que financia projetos na Am\u00e9rica Latina. Presidente do Banco Central entre 2016 e 2019, indicado no governo Michel Temer (MDB), ele foi tamb\u00e9m economista-chefe e s\u00f3cio do Ita\u00fa. Em 2021, foi nomeado diretor do Departamento de Hemisf\u00e9rio Ocidental do FMI.<\/p>\n<p>Ao longo da semana, Guedes j\u00e1 havia afirmado que apostava em uma pessoa com s\u00f3lida experi\u00eancia tanto no setor p\u00fablico quanto no setor privado para indicar para o BID, e que defende que o novo presidente da institui\u00e7\u00e3o fique no cargo por apenas um mandato de 5 anos, e n\u00e3o por v\u00e1rios mandatos como ocorreu antes.<\/p>\n<p>&#8220;Eu conversei com Argentina, conversei com Chile \u2013que vai lan\u00e7ar candidato\u2013, e estou tentando fazer uma alian\u00e7a com a Col\u00f4mbia, foi uma boa reuni\u00e3o. Com a Yellen [secret\u00e1ria do Tesouro dos EUA], eu puxei para um canto, conversei, adiantei um nome para ela, ela aparentemente gostou, mas n\u00e3o h\u00e1 compromisso, disse que seria favor\u00e1vel se fosse consultada&#8221;, disse Guedes a jornalistas na sexta, sem revelar quem seria o indicado.<\/p>\n<p>Questionado se haveria resist\u00eancia de outros pa\u00edses a apoiar um nome indicado pelo governo Jair Bolsonaro (PL) t\u00e3o pr\u00f3ximo \u00e0 elei\u00e7\u00e3o presidencial, Guedes afirmou que houve a preocupa\u00e7\u00e3o de sugerir algu\u00e9m menos alinhado a um ou outro pol\u00edtico.<\/p>\n<p>&#8220;Estou sugerindo algu\u00e9m que esteja mais ou menos fora da pol\u00edtica, que seja conhecido em Washington, que ningu\u00e9m vai dizer que \u00e9 do lado A, B, C ou D. \u00c9 na verdade um quadro t\u00edpico de Washington, um perfil t\u00edpico da burocracia internacional, no bom sentido. Ele tem chance&#8221;, afirmou na sexta.<\/p>\n<p>A vaga da presid\u00eancia do BID est\u00e1 aberta desde que Mauricio Claver-Carone, o \u00faltimo eleito ao cargo, foi deposto em setembro antes de concluir seu mandato de 5 anos ap\u00f3s ser acusado de envolvimento amoroso com uma subordinada.<\/p>\n<p>O Brasil teve outra oportunidade de indicar algu\u00e9m \u00e0 presid\u00eancia, em 2020, mas desistiu ap\u00f3s o ent\u00e3o presidente dos EUA, Donald Trump, pedir diretamente a Bolsonaro que apoiasse Carone. Na \u00e9poca foram cotados Marcos Troyjo (hoje no Novo Banco do Desenvolvimento) e o banqueiro Rodrigo Xavier.<\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1955694\/brasil-quer-ilan-goldfajn-ex-presidente-do-bc-no-comando-do-bid?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; O governo brasileiro quer emplacar na presid\u00eancia do BID (Banco Interamericano de Desenvolvimento)<\/p>\n","protected":false},"author":0,"featured_media":94227,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-94226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=94226"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/94226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/94227"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=94226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=94226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=94226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}