{"id":93968,"date":"2022-10-14T16:08:42","date_gmt":"2022-10-14T19:08:42","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/14\/tre-cassa-diploma-de-vereador-em-mato-grosso-apos-constatar-fraude-em-cota-de-genero\/"},"modified":"2022-10-14T16:08:42","modified_gmt":"2022-10-14T19:08:42","slug":"tre-cassa-diploma-de-vereador-em-mato-grosso-apos-constatar-fraude-em-cota-de-genero","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/14\/tre-cassa-diploma-de-vereador-em-mato-grosso-apos-constatar-fraude-em-cota-de-genero\/","title":{"rendered":"TRE cassa diploma de vereador em Mato Grosso ap\u00f3s constatar fraude em cota de g\u00eanero"},"content":{"rendered":"<p>O Tribunal Regional Eleitoral de Mato Grosso acatou, hoje, por 5 votos a 2, recurso interposto por Neison Costa Lima e o diret\u00f3rio municipal do PT (Partido Trabalhadores) de Campo Verde (130 km de Cuiab\u00e1) e concluiu que houve fraude \u00e0 cota de g\u00eanero na elei\u00e7\u00e3o para vereador, h\u00e1 dois anos. A recorrida foi registrada como candidata ao cargo de vereadora de Campo Verde pelo Partido Social Liberal (PSL)<\/p>\n<p>O pleno reformou a senten\u00e7a da comarca e constatou que huve candidatura feminina fict\u00edcia. Inicialmente, o ju\u00edzo entendeu que a suposta fraude na composi\u00e7\u00e3o da lista de candidatos n\u00e3o teve comprova\u00e7\u00e3o nos autos, em sintonia com a manifesta\u00e7\u00e3o do promotor de Justi\u00e7a Eleitoral. O relator do processo, juiz-membro Abel Sguarezi, teve o mesmo entendimento e votou pelo desprovimento do recurso, mantendo a senten\u00e7a, mesmo entendimento do\u00a0juiz-membro F\u00e1bio Henrique Rodrigues de Moraes Fiorenza.<\/p>\n<p>Mas a desembargadora Nilza Maria P\u00f4ssas de Carvalho decidiu acatar o recurso e reformar a senten\u00e7a de 1\u00ba grau e, \u201cvia de consequ\u00eancia, anular todos os registros de candidaturas apresentados pelo Partido PSL em Campo Verde, cassando o diploma do vereador eleito pelo respectivo partido, Valerindo Martins Sampaio\u201d. Tamb\u00e9m aplicou a san\u00e7\u00e3o de inelegibilidade \u00e0 Lyviane Ferreira Magalh\u00e3es.<\/p>\n<p>Ontem, ao ser retomado o julgamento, os ju\u00edzes-membro Luiz Oct\u00e1vio Oliveira Saboia Ribeiro, Jackson Francisco Coleta Coutinho e Jos\u00e9 Luiz Leite Lindote acompanharam o voto divergente. J\u00e1 o presidente do TRE, desembargador Carlos Alberto Alves da Rocha, que pediu vista do processo e hoje votou seguindo a decis\u00e3o da desembargadora Nilza Maria P\u00f4ssas de Carvalho, e ressaltou que as provas s\u00e3o robustas. \u201cDenoto dos autos que a Sra. Lyviane n\u00e3o recebeu nenhum voto na elei\u00e7\u00e3o, nem mesmo o dela, n\u00e3o apresentou gastos financeiros, n\u00e3o demonstrou qualquer material de campanha, como tamb\u00e9m n\u00e3o comprovou, de forma clarividente, ter participado de qualquer evento de campanha. N\u00e3o obstante, ainda h\u00e1 nos autos print de conversa onde a candidata relata que n\u00e3o queria participar da campanha e estaria ali apenas para n\u00e3o desfalcar o partido\u201d.<\/p>\n<p>Al\u00e9m de Lyviane Ferreira Magalh\u00e3es, ser\u00e3o anulados os registros dos demais candidatos a vereadores lan\u00e7ados pela agremia\u00e7\u00e3o: Geraldo Ferreira da Silva, Ramiro Guarim Fernandes, Claudenir Antonio Kolling, Valerindo Martins Sampaio, Eterno Marins de Carvalho, Raquel Simone Fagundes de Freitas, Nadir Jos\u00e9 Selva, Edna de\u00a0 Queiroz Mascarenhas, Valter Rubens Carlos Barbosa, Vandro Carlos Camargo, Vergina Martins Francisco, Marta Goncalves dos Santos, Rodrigo Silva de Oliveira, Itamar Cerqueira de Sousa, Waldemar Francisco dos Santos, Sebasti\u00e3o Valdomiro Teixeira, Valgremiu Lacerda Santos, Andressa Rodrigueiro Costa, informa a assessoria do TRE.<\/p>\n<p>O vereador Valerindo Martins Sampaio, que teve o diploma eleitoral cassado pelo TRE, poder\u00e1 recorrer da decis\u00e3o.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Regional Eleitoral de Mato Grosso acatou, hoje, por 5 votos a 2, recurso<\/p>\n","protected":false},"author":0,"featured_media":93969,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-93968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93968"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93969"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}