{"id":93719,"date":"2022-10-12T12:08:14","date_gmt":"2022-10-12T15:08:14","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/12\/ator-de-chocolate-com-pimenta-morre-aos-75-anos-em-mg-apos-mal-subito\/"},"modified":"2022-10-12T12:08:14","modified_gmt":"2022-10-12T15:08:14","slug":"ator-de-chocolate-com-pimenta-morre-aos-75-anos-em-mg-apos-mal-subito","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/12\/ator-de-chocolate-com-pimenta-morre-aos-75-anos-em-mg-apos-mal-subito\/","title":{"rendered":"Ator de &#8216;Chocolate com Pimenta&#8217; morre aos 75 anos em MG ap\u00f3s mal s\u00fabito"},"content":{"rendered":"<p>(UOL\/FOLHAPRESS) &#8211; O ator M\u00e1rio C\u00e9sar Camargo morreu na \u00faltima segunda-feira (10), aos 75 anos, em Belo Horizonte (MG), ap\u00f3s sofrer um mal s\u00fabito.<br \/>A informa\u00e7\u00e3o foi confirmada ao UOL pela filha do ator, Laura.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O artista nasceu em Mar\u00edlia, interior de S\u00e3o Paulo, mas morava em Belo Horizonte desde 1988.<\/p>\n<p>M\u00e1rio C\u00e9sar Camargo ficou famoso ap\u00f3s trabalhar em tramas das emissoras da TV Globo, RecordTV e TV Bandeirantes.<\/p>\n<p>Na emissora carioca, ele atuou nas novelas &#8220;Terra Nostra&#8221;, &#8220;Cora\u00e7\u00e3o de Estudante&#8221;, Chocolate com Pimenta, que est\u00e1 no ar em uma edi\u00e7\u00e3o especial, &#8220;Come\u00e7ar de Novo&#8221; e &#8220;Insensato Cora\u00e7\u00e3o&#8221;.<\/p>\n<p>Ainda na TV Globo, o artista tamb\u00e9m ganhou pap\u00e9is nas s\u00e9ries &#8220;Sob Nova Dire\u00e7\u00e3o&#8221; e &#8220;Supermax&#8221;.<\/p>\n<p>J\u00e1 nos cinemas, M\u00e1rio C\u00e9sar Camargo atuou nas tramas &#8220;Linha de Passe&#8221;, &#8220;Pequenas Hist\u00f3rias&#8221;, &#8220;Veias e Vinhos&#8221; e &#8220;Narradores de Jav\u00e9&#8221;.<\/p>\n<p>Nas redes sociais, amigos do ator fizeram postagens de homenagem ao artista destacando seus trabalhos na televis\u00e3o.<\/p>\n<p>O \u00faltimo trabalho de Mario C\u00e9sar Camargo na televis\u00e3o foi, em 2016, na s\u00e9rie &#8220;Supermax&#8221;. Ele interpretou Tim\u00f3teo, um m\u00e9dico reformado pelo ex\u00e9rcito.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/1954497\/ator-de-chocolate-com-pimenta-morre-aos-75-anos-em-mg-apos-mal-subito?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(UOL\/FOLHAPRESS) &#8211; O ator M\u00e1rio C\u00e9sar Camargo morreu na \u00faltima segunda-feira (10), aos 75 anos,<\/p>\n","protected":false},"author":0,"featured_media":93720,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-93719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93719"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93720"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}