{"id":93512,"date":"2022-10-10T19:08:10","date_gmt":"2022-10-10T22:08:10","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/10\/cotacao-do-boi-e-vaca-em-mato-grosso-tem-mais-uma-semana-de-queda\/"},"modified":"2022-10-10T19:08:10","modified_gmt":"2022-10-10T22:08:10","slug":"cotacao-do-boi-e-vaca-em-mato-grosso-tem-mais-uma-semana-de-queda","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/10\/cotacao-do-boi-e-vaca-em-mato-grosso-tem-mais-uma-semana-de-queda\/","title":{"rendered":"Cota\u00e7\u00e3o do boi e vaca em Mato Grosso tem mais uma semana de queda"},"content":{"rendered":"<p>O Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA) informou, esta tarde, que depois de v\u00e1rias semanas<br \/>\nconsecutivas de queda intensa no indicador da arroba do boi gordo, na \u00faltima semana a varia\u00e7\u00e3o foi de -0,43% no comparativo semanal, fechando na \u00faltima sexta-feira a R$ 253,99.<\/p>\n<p>A oferta mais t\u00edmida de f\u00eameas ao abate fez com que a arroba da vaca gorda registrasse recuo de apenas 0,30% ante a<br \/>\nsemana passada, sendo cotada a R$ 242,73.<\/p>\n<p>Com a oferta de bovinos acima do esperado para o per\u00edodo, o contrato corrente da bolsa registrou queda de 1,76% no<br \/>\ncomparativo semanal, conclui o instituto, no boletim semanal da pecu\u00e1ria.<\/p>\n<p>Agronot\u00edcias \u2013 S\u00f3 Not\u00edcias<br \/>\n<a href=\"https:\/\/www.sonoticias.com.br\/agronoticias\/cotacao-do-boi-e-vaca-em-mato-grosso-tem-mais-uma-semana-de-queda\/\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Mato-grossense de Economia Agropecu\u00e1ria (IMEA) informou, esta tarde, que depois de v\u00e1rias semanas<\/p>\n","protected":false},"author":0,"featured_media":93513,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-93512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronoticias"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93512"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93513"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}