{"id":93419,"date":"2022-10-10T11:08:20","date_gmt":"2022-10-10T14:08:20","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/10\/ticiane-pinheiro-anuncia-morte-da-sogra-a-mae-de-cesar-tralli\/"},"modified":"2022-10-10T11:08:20","modified_gmt":"2022-10-10T14:08:20","slug":"ticiane-pinheiro-anuncia-morte-da-sogra-a-mae-de-cesar-tralli","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/10\/ticiane-pinheiro-anuncia-morte-da-sogra-a-mae-de-cesar-tralli\/","title":{"rendered":"Ticiane Pinheiro anuncia morte da sogra, a m\u00e3e de C\u00e9sar Tralli"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Morreu Edna Tralli, m\u00e3e do jornalista da Globo C\u00e9sar Tralli. A informa\u00e7\u00e3o foi divulgada pela nora, a apresentadora Ticiane Pinheiro. As causas n\u00e3o foram reveladas.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;V\u00e1 em paz, sogrinha. J\u00e1 estou com saudades do seu abra\u00e7o, do seu carinho, das nossas conversas, do seu amor. Te amarei para sempre. Que Deus te receba de bra\u00e7os abertos&#8221;, postou a apresentadora.<br \/>Enteada do jornalista, Rafaella Justus tamb\u00e9m prestou uma homenagem. &#8220;Pense em uma mulher de cora\u00e7\u00e3o gigante, que n\u00e3o arruma intriga, \u00e9 super amorosa e que \u00e9 uma super av\u00f3. Essa era ela, Edna Tralli, a av\u00f3 que a vida me deu. Tive o privil\u00e9gio enorme de conviver com voc\u00ea e aprender tanto! Me despedir assim do nada foi muito dif\u00edcil, estou sentindo muito a sua falta&#8221;, escreveu.<\/p>\n<p>At\u00e9 a publica\u00e7\u00e3o deste texto, C\u00e9sar ainda n\u00e3o havia se pronunciado a respeito da perda.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1953665\/ticiane-pinheiro-anuncia-morte-da-sogra-a-mae-de-cesar-tralli?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Morreu Edna Tralli, m\u00e3e do jornalista da Globo C\u00e9sar Tralli.<\/p>\n","protected":false},"author":0,"featured_media":93420,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-93419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93419"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93420"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}