{"id":93407,"date":"2022-10-10T09:08:13","date_gmt":"2022-10-10T12:08:13","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/10\/empresas-de-guarda-moveis-agora-priorizam-o-e-commerce\/"},"modified":"2022-10-10T09:08:13","modified_gmt":"2022-10-10T12:08:13","slug":"empresas-de-guarda-moveis-agora-priorizam-o-e-commerce","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/10\/empresas-de-guarda-moveis-agora-priorizam-o-e-commerce\/","title":{"rendered":"Empresas de guarda-m\u00f3veis agora priorizam o e-commerce"},"content":{"rendered":"<p>A falta de galp\u00f5es perto da casa do consumidor para agilizar as entregas do e-commerce est\u00e1 mudando a paisagem da cidade de S\u00e3o Paulo e abrindo novas frentes para as empresas de armazenagem. A GoodStorage, por exemplo, que come\u00e7ou em 2013 como um guarda-m\u00f3veis, hoje se posiciona como uma empresa de log\u00edstica urbana, oferecendo armazenagem para pessoas f\u00edsicas e empresas.<\/p>\n<p>Um exemplo dessa transforma\u00e7\u00e3o foi a compra da f\u00e1brica de trens da Alstom, na Lapa, na zona oeste da cidade. Com a ida da ind\u00fastria para Taubat\u00e9 (SP), ficou vago um terreno de 80 mil metros quadrados, com 65 mil m\u00b2 de galp\u00f5es.<\/p>\n<\/p>\n<p>&#8220;Estamos reformando esses galp\u00f5es, que v\u00e3o dar origem a um parque log\u00edstico no cora\u00e7\u00e3o da Lapa&#8221;, conta Thiago Cordeiro CEO da GoodStorage. O empreendimento come\u00e7a a funcionar em fevereiro e j\u00e1 tem uma parte pr\u00e9-locada.<\/p>\n<\/p>\n<p>A f\u00e1brica da Alstom foi adquirida antes da pandemia, assim como outros im\u00f3veis, v\u00e1rios deles ocupados por ind\u00fastrias. <\/p>\n<\/p>\n<p>Todos est\u00e3o para dentro das Marginais e com localiza\u00e7\u00e3o estrat\u00e9gica, a fim de serem transformados em galp\u00f5es de armazenagem voltados para entregas r\u00e1pidas.<\/p>\n<\/p>\n<p>Hoje a companhia tem sete parques log\u00edsticos urbanos, que somam uma \u00e1rea de 150 mil m\u00b2 e investimentos de US$ 150 milh\u00f5es. Quatro j\u00e1 est\u00e3o em opera\u00e7\u00e3o, com 90% de ocupa\u00e7\u00e3o.<\/p>\n<\/p>\n<p>Em cinco anos, o plano \u00e9 ter 500 mil m\u00b2 de galp\u00f5es log\u00edsticos na cidade de S\u00e3o Paulo, com investimentos adicionais de US$ 250 milh\u00f5es. &#8220;A despeito do juro alto n\u00e3o ser favor\u00e1vel ao investimento imobili\u00e1rio, continuaremos investindo e bastante, porque falta infraestrutura.&#8221;<\/p>\n<\/p>\n<p><b>Pandemia<\/b><\/p>\n<\/p>\n<p>Outra empresa que mudou o posicionamento foi a Unlog. Come\u00e7ou h\u00e1 dois anos como uma plataforma de loca\u00e7\u00e3o de vagas de estacionamento, mas n\u00e3o deu certo. <\/p>\n<\/p>\n<p>Michele D&#8217;Ippolito, s\u00f3cio diretor da companhia, diz que a sa\u00edda foi virar a empresa para a log\u00edstica urbana, no qual o aluguel \u00e9 mais valorizado. Foram ent\u00e3o abertos pequenos galp\u00f5es, com tamanhos que variam entre 200 e 1.000 m\u00b2, que est\u00e3o espalhados por bairros dentro de grandes cidades.<\/p>\n<\/p>\n<p>&#8220;Miramos numa formiguinha e acertamos num elefante&#8221;, afirma D&#8217;Ippolito. Com a mudan\u00e7a, imediatamente ele conseguiu conquistar clientes como Ambev, Mercado Livre, Americanas e outras gigantes.<\/p>\n<\/p>\n<p>O empres\u00e1rio explica que &#8220;granulariza\u00e7\u00e3o&#8221; da armazenagem dentro dos grandes centros \u00e9 a nova tend\u00eancia. Com isso, passaram a ser aproveitados os espa\u00e7os mais variados: de lojas desativadas a galp\u00f5es e tamb\u00e9m parte de estacionamentos ociosos. &#8220;Somos bem ecl\u00e9ticos, e o nosso modelo \u00e9 bem h\u00edbrido.&#8221;<\/p>\n<\/p>\n<p>Na Rua 25 de Mar\u00e7o, polo de com\u00e9rcio popular do centro da capital, a empresa ocupa parte de um estacionamento. A \u00e1rea alugada foi transformada em ponto de armazenagem em cont\u00eaineres e tamb\u00e9m \u00e9 aproveitada para o transbordo e retirada de itens.<\/p>\n<\/p>\n<p>Na Vila Ol\u00edmpia, zona sul da cidade, a companhia tem uma \u00e1rea de armazenagem de 400 m\u00b2, dividida em pequenos hubs log\u00edsticos. Eles s\u00e3o alugados pelo varejo online, como Amaro, Riachuelo e empresas como a Infracommerce, voltada \u00e0 parte de implementa\u00e7\u00e3o de e-commerce para as ind\u00fastrias. <\/p>\n<\/p>\n<p>Ali\u00e1s, ind\u00fastrias de bens de consumo, como Philip Morris e Canon, que est\u00e3o nessa unidade, s\u00e3o os principais clientes da companhia.<\/p>\n<\/p>\n<p><b>Pr\u00e9-Sal<\/b><\/p>\n<\/p>\n<p>&#8220;Para a gente, a pandemia foi m\u00e1gica&#8221;, diz o empres\u00e1rio, que no meio da crise sanit\u00e1ria da covid-19 viu seu neg\u00f3cio dar um salto. &#8220;Em 2021, crescemos o faturamento em 1.600%.&#8221; <\/p>\n<\/p>\n<p>O neg\u00f3cio deu t\u00e3o certo que foi criada uma divis\u00e3o espec\u00edfica de armaz\u00e9ns, a Undock. Hoje s\u00e3o 28 unidades que somam cerca de 20 mil m\u00b2 de \u00e1rea de armazenagem em mais de 20 cidades. <\/p>\n<\/p>\n<p>A meta \u00e9 ter 700 hubs de armazenagem em seis anos. E a pr\u00f3xima fronteira a ser explorada ser\u00e1 o &#8220;pr\u00e9-sal&#8221;, brinca o empres\u00e1rio. <\/p>\n<\/p>\n<p>Ele se refere \u00e0s \u00e1reas subterr\u00e2neas das grandes cidades que est\u00e3o ociosas e necessitam de muita tecnologia para serem exploradas. &#8220;Esse \u00e9 o pr\u00f3ximo passo que a gente enxerga como sendo o metro quadrado com grande potencial de ser ressignificado para a log\u00edstica.&#8221;<\/p>\n<\/p>\n<p> As informa\u00e7\u00f5es s\u00e3o do jornal <b>O Estado de S. Paulo.<\/b><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1953639\/empresas-de-guarda-moveis-agora-priorizam-o-e-commerce?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A falta de galp\u00f5es perto da casa do consumidor para agilizar as entregas do e-commerce<\/p>\n","protected":false},"author":0,"featured_media":93408,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-93407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93407"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93408"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}