{"id":93205,"date":"2022-10-08T13:08:13","date_gmt":"2022-10-08T16:08:13","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/08\/ultimo-capitulo-de-pantanal-tem-beijo-gay-veja-que-aconteceu-com-cada-personagem\/"},"modified":"2022-10-08T13:08:13","modified_gmt":"2022-10-08T16:08:13","slug":"ultimo-capitulo-de-pantanal-tem-beijo-gay-veja-que-aconteceu-com-cada-personagem","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/08\/ultimo-capitulo-de-pantanal-tem-beijo-gay-veja-que-aconteceu-com-cada-personagem\/","title":{"rendered":"\u00daltimo cap\u00edtulo de &#8216;Pantanal&#8217; tem beijo gay; veja que aconteceu com cada personagem"},"content":{"rendered":"<p>ANA CORA LIMA<br \/>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; O \u00faltimo cap\u00edtulo de &#8220;Pantanal&#8221; reservou fortes emo\u00e7\u00f5es para os telespectadores que acompanharam a novela nos quase sete meses em que ela foi exibida no hor\u00e1rio nobre da Globo. A trama escrita por Bruno Luperi, um remake da obra de Benedito RuyBarbosa, exibida h\u00e1 32 anos na extinta Manchete, teve um dos finais que n\u00e3o foi exibido em 1990: O beijo gay entre os pe\u00f5es vividos por Silvero Pereira e Thommy Schiavo. Eles se beijaram durante a festa do casamento coletivo na fazenda de Z\u00e9 Le\u00f4ncio.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Outro momento in\u00e9dito foi a presen\u00e7a de Maria Bruaca no casamento. A personagem de Isabel Teixeira \u00e9 quem avisa Zaquieu (Silvero Pereira) sobre o interesse de Zoinho. Quando o pe\u00e3o tira o o amigo de Alcides para dan\u00e7ar, ela cita um dos bord\u00f5es mais populares da dramaturgia: &#8220;T\u00f4 certa ou t\u00f4 errada?&#8221;, sacudindo a pulseira tal como o ic\u00f4nico Sinhozinho Malta, de &#8220;Roque Santeiro&#8221; (1985).<\/p>\n<p><span class=\"news_bold news_italic\">ABAIXO OS DESFECHOS DOS PRINCIPAIS PERSONAGENS:<\/span><br \/>JUMA e JOVE (Alanis e Jesu\u00edta Barbosa) &#8211; Com a morte de Z\u00e9 Le\u00f4ncio, Jove assumir\u00e1 os neg\u00f3cios da fam\u00edlia e Juma decide ajudar o companheiro vivendo para sempre na fazenda que era do sogro.<\/p>\n<p>Z\u00c9 LE\u00d4NCIO (Marcos Palmeira) &#8211; Um dia depois da festa, Z\u00e9 Le\u00f4ncio acorda com uma forte dor no peito e, entre uma crise e outra, ele finalmente consegue ver a figura do pai na foto. O fazendeiro morre logo em seguida e fica frente a frente com seu pai. O Velho do Rio diz que de agora em diante, Z\u00e9 Le\u00f4ncio deve cuidar de seus filhos e netos, como ele fez durante todos esses anos. Ele vira o novo V\u00e9io do Rio.<\/p>\n<p>FIL\u00d3 (Dira Paes) &#8211; Ap\u00f3s a morte de Z\u00e9 Le\u00f4ncio, Fil\u00f3 assume os neg\u00f3cios da fam\u00edlia e sofre pelos cantos com saudade do fazendeiro, que chegou a realizar o seu sonho de casamento, mas ele morre no dia seguinte \u00e0 festa. Vi\u00fava, ela vai herdar uma &#8220;heran\u00e7a maldita&#8221; do marido: ela n\u00e3o consegue enxergar o V\u00e9io do Rio, que vai surgir passeando e conversando com os netos.<\/p>\n<p>Z\u00c9 LUCAS E IRMA (Irandhir Santos e Camila Morgado) &#8211; Z\u00e9 Lucas e Irma terminam juntos, criando o filho da mulher com Trindade. Os dois tocam os projetos juntos como a escolinha da \u00e1rea. O filho mais velho de Z\u00e9 Le\u00f4ncio vira pol\u00edtico.<\/p>\n<p>TADEU E ZEFA (Jos\u00e9 Loreto e Paula Barbosa) &#8211; Dono da sonhada sela de prata e &#8220;filho do cora\u00e7\u00e3o&#8221; de Z\u00e9 Le\u00f4ncio, Tadeu se casa com Zefa, gr\u00e1vida. O pe\u00e3o continua tocando a fazenda como o pai.<\/p>\n<p>V\u00c9IO DO RIO (Osmar Prado) &#8211; Ao encontrar o filho, ele passou o bast\u00e3o de guardi\u00e3o do Pantanal. O anci\u00e3o se transforma em sucuri pela \u00faltima vez e desaparece.<\/p>\n<p>TEN\u00d3RIO (Murilo Ben\u00edcio) &#8211; Depois de colecionar inimigos ao longo da vida, Ten\u00f3rio morreu ap\u00f3s uma luta com Alcides. O vil\u00e3o foi atravessado por uma zagaia e, enquanto agonizava na beira do rio, acaba sendo engolido pelo V\u00e9io do Rio em forma de sucuri.<\/p>\n<p>BRUACA E ALCIDES (Isabel Teixeira e Juliano Cazarr\u00e9) &#8211; Depois de muito sofrimento, Bruaca e Alcides se mudam e se tornam fazendeiros pr\u00f3speros em Sarandi. Eles voltam para o casamento triplo na fazenda.<\/p>\n<p>ZULEICA (Aline Borges) &#8211; Com a morte de Ten\u00f3rio, Zuleica decide cuidar da fazenda e prosperar os neg\u00f3cios da fam\u00edlia no Pantanal. Os dois se aproximam na festa de casamento dos vizinhos e s\u00f3cios, e tudo d\u00e1 a entender que ali come\u00e7ava uma hist\u00f3ria de amor na novela. Mais uma,.<\/p>\n<p>ZAQUIEU &#8211; Ele aceita o convite do amigo Alcides para se mudar e ajudar o novo fazendeiro a cuidar das terras em Sarandi com Maria Bruaca. Antes disso, Zaquieu se envolve com um pe\u00e3o, com direito a beijinho na boca na festa de casamento.<\/p>\n<p>MUDA E TIB\u00c9RIO (Bella Campos e Guito) &#8211; Vingada com a morte de Ten\u00f3rio, Muda retoma o casamento com Tib\u00e9rio e, logo depois, ela fica gr\u00e1vida. Os dois ainda recebem a terra de Juma para come\u00e7ar a criar gado e ter a sua pr\u00f3pria fazenda.<\/p>\n<p>GUTA E MARCELO (Julia Dalavia e Lucas Leto) &#8211; O casal segue na fazenda cuidando dos neg\u00f3cios e do filho, Ot\u00e1vio.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1953249\/ultimo-capitulo-de-pantanal-tem-beijo-gay-veja-que-aconteceu-com-cada-personagem?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA CORA LIMARIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; O \u00faltimo cap\u00edtulo de &#8220;Pantanal&#8221; reservou fortes<\/p>\n","protected":false},"author":0,"featured_media":93206,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-93205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93205"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93206"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}