{"id":93203,"date":"2022-10-08T13:08:08","date_gmt":"2022-10-08T16:08:08","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/08\/mundo-se-recupera-da-crise-gerada-pela-pandemia-mas-perde-ritmo\/"},"modified":"2022-10-08T13:08:08","modified_gmt":"2022-10-08T16:08:08","slug":"mundo-se-recupera-da-crise-gerada-pela-pandemia-mas-perde-ritmo","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/08\/mundo-se-recupera-da-crise-gerada-pela-pandemia-mas-perde-ritmo\/","title":{"rendered":"Mundo se recupera da crise gerada pela pandemia mas perde ritmo"},"content":{"rendered":"<p>Embora a economia global tenha se recuperado dos estragos provocados pela pandemia de coronav\u00edrus, o crescimento mundial ainda n\u00e3o ganhou tra\u00e7\u00e3o. E pior: os choques detonados pela guerra entre R\u00fassia e Ucr\u00e2nia e a alta de juros adotada pelos principais bancos centrais devem dificultar o cen\u00e1rio daqui em diante.<\/p>\n<p>Levantamento do Ita\u00fa com as 28 maiores economias mostra que o Produto Interno Bruto (PIB) global terminou o segundo trimestre deste ano 3,9% acima do observado no quatro trimestre de 2019, o \u00faltimo antes da pandemia. O problema \u00e9 que a tend\u00eancia de crescimento desses pa\u00edses est\u00e1 2,5% mais baixa. Na pr\u00e1tica, quer dizer que cresceram, mas num ritmo fraco desde o in\u00edcio da crise sanit\u00e1ria.<\/p>\n<\/p>\n<p>&#8220;A maioria dos pa\u00edses voltou ao n\u00edvel pr\u00e9-pandemia e retornou mais ou menos no per\u00edodo que a gente acreditava, em 2021, alguns at\u00e9 voltaram em 2022. Foram poucos os que n\u00e3o se recuperaram&#8221;, afirma Guilherme Martins, economista do Ita\u00fa BBA. &#8220;Mas a tend\u00eancia do PIB da maioria dos pa\u00edses est\u00e1 abaixo (do observado) no per\u00edodo de pr\u00e9-pandemia. Economias que cresciam bastante est\u00e3o crescendo menos.&#8221;<\/p>\n<\/p>\n<p>S\u00e3o tr\u00eas grandes fatores que explicam esse cen\u00e1rio de desempenho mais fraco.<\/p>\n<\/p>\n<p>O primeiro \u00e9 a pol\u00edtica &#8220;covid zero&#8221; praticada nos pa\u00edses da \u00c1sia, sobretudo na China. Nos per\u00edodos em que h\u00e1 um aumento de casos da doen\u00e7a, os governos locais voltam a adotar duras medidas de distanciamento social com o objetivo de evitar o aumento de cont\u00e1gios. O segundo tem a ver com a guerra entre R\u00fassia e Ucr\u00e2nia, que provocou diversos choques, como a disparada do barril do petr\u00f3leo no mercado internacional.<\/p>\n<\/p>\n<p><b>Aperto nos juros<\/b><\/p>\n<\/p>\n<p>Por fim, o aumento da infla\u00e7\u00e3o global tem levado os principais bancos centrais do mundo a apertar a pol\u00edtica monet\u00e1ria. Juros mais altos encarecem o consumo para as fam\u00edlias e o investimento para as empresas, prejudicando o ritmo da atividade econ\u00f4mica. N\u00e3o \u00e0 toa, parte dos analistas n\u00e3o descarta recess\u00e3o para Europa e Estados Unidos.<\/p>\n<\/p>\n<p>No m\u00eas passado, por exemplo, Federal Reserve (Fed, banco central norte-americano) subiu as suas taxas de juros em 0,75 ponto porcentual pela terceira vez seguida. Os juros foram para a faixa entre 3% e 3,25%. A autoridade monet\u00e1ria dos EUA tamb\u00e9m indicou que o aperto monet\u00e1rio deve prosseguir. Na leitura dos economistas, as taxas norte-americanas podem chegar a 5%.<\/p>\n<\/p>\n<p>&#8220;\u00c9 um cen\u00e1rio que mostra que a supera\u00e7\u00e3o da crise provocada pela covid foi muito mais r\u00e1pida do que a de outras recess\u00f5es, mas o quadro piorou depois da guerra entre R\u00fassia e Ucr\u00e2nia e das sinaliza\u00e7\u00f5es mais duras de banco centrais, particularmente do Federal Reserve&#8221;, diz Br\u00e1ulio Borges, pesquisador associado do Instituto Brasileiro de Economia (Ibre), da Funda\u00e7\u00e3o Get\u00falio Vargas (FGV). <\/p>\n<\/p>\n<p><b>Quadro recessivo<\/b><\/p>\n<\/p>\n<p>Em raz\u00e3o das dificuldades da economia global, a diretora-gerente do Fundo Monet\u00e1rio Internacional (FMI), Kristalina Georgieva, antecipou nesta semana que o \u00f3rg\u00e3o deve rever as suas previs\u00f5es de crescimento para 2023 em relat\u00f3rio a ser divulgado na pr\u00f3xima semana. Com percep\u00e7\u00e3o semelhante, a Organiza\u00e7\u00e3o para a Coopera\u00e7\u00e3o e Desenvolvimento Econ\u00f4mico (OCDE) passou a projetar um crescimento de apenas 2,2% para o mundo em 2023. Em junho, previa 2,8%. Para este ano, manteve a sua estimativa em 3%.<\/p>\n<\/p>\n<p>&#8220;\u00c9 um n\u00famero que flerta com uma recess\u00e3o moderada, porque a gente tem de lembrar que a popula\u00e7\u00e3o mundial aumenta 1,1% ao ano&#8221;, afirma Br\u00e1ulio Borges, pesquisador associado do Instituto Brasileiro de Economia (Ibre), da Funda\u00e7\u00e3o Get\u00falio Vargas (FGV). &#8220;Um PIB mundial que cresce 2,2% &#8211; como prev\u00ea a OCDE &#8211; traz um ganho muito pequeno em termos per capita.&#8221;<\/p>\n<\/p>\n<p>A OCDE vem piorando sucessivamente as suas proje\u00e7\u00f5es para o desempenho da economia mundial, lembra Br\u00e1ulio. No fim do ano passado, a organiza\u00e7\u00e3o previa avan\u00e7o do PIB do mundo de 4,5%, em 2022, e de 3,5% em 2023.<\/p>\n<\/p>\n<p>&#8220;Era um cen\u00e1rio vislumbrado n\u00e3o s\u00f3 pela OCDE, mas por boa parte dos analistas no final de 2021 e no come\u00e7o deste ano. \u00c9 mais ou menos o que o mundo cresceu de 2015 at\u00e9 2019, antes da pandemia&#8221;, afirma o pesquisador.<\/p>\n<\/p>\n<p><b>&#8216;Capital humano&#8217;<\/b><\/p>\n<\/p>\n<p>N\u00e3o \u00e9 s\u00f3 no curto e no m\u00e9dio prazos que o crescimento global pode ser mais fraco do que o esperado diante desse cen\u00e1rio mais complicado.<\/p>\n<\/p>\n<p>Se nada for feito, os analistas dizem que os impactos da pandemia na qualidade do ensino devem afetar o desempenho da produtividade, comprometendo at\u00e9 o futuro da economia.<\/p>\n<\/p>\n<p>&#8220;As crian\u00e7as ficaram muito tempo fora da escola, mais no Brasil do que em outros pa\u00edses. A gente viu os dados mostrando quedas muito severas do n\u00edvel de aprendizado das crian\u00e7as nesse bi\u00eanio da pandemia&#8221;, diz Br\u00e1ulio.<\/p>\n<\/p>\n<p>Na leitura dele, \u00e9 poss\u00edvel que haja &#8220;uma gera\u00e7\u00e3o perdida&#8221; se os pa\u00edses n\u00e3o desenvolverem pol\u00edticas p\u00fablicas educacionais para superar esse per\u00edodo de piora na qualidade da educa\u00e7\u00e3o.<\/p>\n<\/p>\n<p>&#8220;Se nada for feito, haver\u00e1 um dano de capital humano e que vai se refletir l\u00e1 na frente sobre a produtividade da economia mundial e a capacidade de inova\u00e7\u00e3o. Corremos o risco de ver uma gera\u00e7\u00e3o perdida&#8221;, afirma o pesquisador do Ibre.<\/p>\n<p> As informa\u00e7\u00f5es s\u00e3o do jornal <b>O Estado de S. Paulo.<\/b><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1953250\/mundo-se-recupera-da-crise-gerada-pela-pandemia-mas-perde-ritmo?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embora a economia global tenha se recuperado dos estragos provocados pela pandemia de coronav\u00edrus, o<\/p>\n","protected":false},"author":0,"featured_media":93204,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-93203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93203"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93204"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}