{"id":93184,"date":"2022-10-07T22:08:21","date_gmt":"2022-10-08T01:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/gabriela-prioli-se-recusa-a-falar-sobre-corte-de-verba-na-educacao-e-e-criticada\/"},"modified":"2022-10-07T22:08:21","modified_gmt":"2022-10-08T01:08:21","slug":"gabriela-prioli-se-recusa-a-falar-sobre-corte-de-verba-na-educacao-e-e-criticada","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/gabriela-prioli-se-recusa-a-falar-sobre-corte-de-verba-na-educacao-e-e-criticada\/","title":{"rendered":"Gabriela Prioli se recusa a falar sobre corte de verba na educa\u00e7\u00e3o e \u00e9 criticada"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A advogada Gabriela Prioli, 36, gr\u00e1vida de sete meses, se recusou a dar a sua opini\u00e3o a pedido de seguidores sobre o governo Jair Bolsonaro bloquear R$ 2,4 bilh\u00f5es do or\u00e7amento do MEC (Minist\u00e9rio da Educa\u00e7\u00e3o) deste ano.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Recebi mensagens: &#8216;Gabi fala sobre o corte na educa\u00e7\u00e3o&#8217;. Galera, estou em Nova York fazendo o enxoval da minha filha. Mas assim n\u00e3o vou [falar sobre], talvez semana que vem&#8221;, disse.<\/p>\n<p>No Twitter, o nome dela virou um dos assuntos mais comentados como se ela n\u00e3o estivesse muito preocupada com a situa\u00e7\u00e3o. &#8220;Por que voc\u00ea quer saber o que a Gabriela Prioli, rica, gr\u00e1vida e em Nova York tem a dizer sobre educa\u00e7\u00e3o p\u00fablica? \u00c0s vezes o problema nem est\u00e1 nela e sim em quem deposita essa import\u00e2ncia&#8221;, postou um seguidor.<\/p>\n<p>&#8220;A Gabriela Prioli olhando pra c\u00e2mera com cara de desd\u00e9m falando que est\u00e1 em NY comprando enxoval da filha enquanto o pa\u00eds agoniza. \u00c9 o retrato da branquitude cafona&#8221;, opinou outra.<\/p>\n<p>Ap\u00f3s a repercuss\u00e3o, Prioli rebateu. Em texto divulgado em seus Stories, se disse &#8220;indignada&#8221;. &#8220;Sabe qual \u00e9 o erro que a gente comete? \u00c9 achar que estamos entre amigos. Que constru\u00edmos aqui alguma intimidade&#8221;, come\u00e7ou.<\/p>\n<p>&#8220;Me perdoem aqueles que durante os \u00faltimos dias me mandaram in\u00fameras mensagens carinhosas me encorajando a descansar. Voc\u00eas s\u00e3o maioria e n\u00e3o merecem esse desabafo. Mas eu acordei de um cochilo e me deparei com esse absurdo e estou aqui indignada, precisando desabafar&#8221;, concluiu.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1953023\/gabriela-prioli-se-recusa-a-falar-sobre-corte-de-verba-na-educacao-e-e-criticada?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A advogada Gabriela Prioli, 36, gr\u00e1vida de sete meses, se<\/p>\n","protected":false},"author":0,"featured_media":93185,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-93184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93184"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93185"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}