{"id":93156,"date":"2022-10-07T18:08:04","date_gmt":"2022-10-07T21:08:04","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/prefeitos-de-sinop-lucas-do-rio-verde-e-mutum-elogiam-governo-de-mt-por-assumir-a-br-163\/"},"modified":"2022-10-07T18:08:04","modified_gmt":"2022-10-07T21:08:04","slug":"prefeitos-de-sinop-lucas-do-rio-verde-e-mutum-elogiam-governo-de-mt-por-assumir-a-br-163","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/prefeitos-de-sinop-lucas-do-rio-verde-e-mutum-elogiam-governo-de-mt-por-assumir-a-br-163\/","title":{"rendered":"Prefeitos de Sinop, Lucas do Rio Verde e Mutum elogiam governo de MT por assumir a BR-163"},"content":{"rendered":"<p>O prefeito de Lucas do Rio Verde, Miguel Vaz, disse que a decis\u00e3o do governo do Estado em assumir a gest\u00e3o da rodovia, de Sinop a divisa com Mato Grosso do Sul,\u00a0 \u00e9 \u201ccorajosa\u201d e proporcionar\u00e1 as solu\u00e7\u00f5es desejadas, como a duplica\u00e7\u00e3o do Posto Gil a Nova Mutum, Lucas, Sorriso e Sinop (230 km) em um tempo menor.<\/p>\n<p>\u201cEste \u00e9 mais um grande passo do Governo do Estado, uma decis\u00e3o corajosa e arrojada de tomar para si essa responsabilidade, a qual temos a certeza de que, nas m\u00e3os do governador Mauro Mendes e do vice-governador Otaviano Pivetta. Esse projeto vai ser executado com \u00eaxito e em tempo recorde\u201d, disse.<\/p>\n<p>A MT Participa\u00e7\u00f5es e Projetos (MT Par), do governo estadual, assumir\u00e1 como concession\u00e1ria e a Rota do Oeste deixar\u00e1 de operar. O investimento a curto prazo ser\u00e1 R$ 1,2 bilh\u00e3o para a duplica\u00e7\u00e3o da BR-163 e o plano de ataque, apresentado esta semana, quando foi assinado termo de ajustamento, entre o governador Mauro Mendes, o ministro da Infraestrutura Marcelo Carvalho, ministros do Tribunal de Contas da Uni\u00e3o e diretoria da Ag\u00eancia Nacional de Transporte Terrestre, prev\u00ea passarelas nas cidades no eixo da rodovia.<\/p>\n<p>O prefeito de Sinop e presidente da Comiss\u00e3o BR-163 do Cons\u00f3rcio Intermunicipal de Desenvolvimento Econ\u00f4mico e Socioambiental do Alto do Rio Teles Pires, (Cidesa),\u00a0Roberto Dorner, afirma que a obra de duplica\u00e7\u00e3o \u00e9 um dos maiores clamores da popula\u00e7\u00e3o. \u201cCom a iniciativa em assumir a sua concess\u00e3o, o governo estadual resolver\u00e1 um anseio que nos assola h\u00e1 muitos anos e traz preju\u00edzos enormes para os munic\u00edpios, principalmente aos do eixo, j\u00e1 que in\u00fameras vidas s\u00e3o perdidas naquele trecho\u201d, declarou.<\/p>\n<p>Mauro Mendes ressaltou que a BR-163 \u00e9 motivo de preocupa\u00e7\u00e3o e aten\u00e7\u00e3o do governo estadual, que h\u00e1 anos busca uma solu\u00e7\u00e3o para os entraves envolvendo a rodovia. Isso porque, al\u00e9m de desempenhar um papel expressivo na economia estadual e do pa\u00eds, sendo um importante corredor log\u00edstico e o principal meio de escoamento da produ\u00e7\u00e3o agr\u00edcola da Regi\u00e3o Centro-Oeste, a BR-163 tamb\u00e9m \u00e9 a principal via de tr\u00e2nsito de cerca de 50% da popula\u00e7\u00e3o mato-grossense.\u00a0 \u201c<\/p>\n<p>A proposta do governo de Mato Grosso \u00e9 acelerar as obras de duplica\u00e7\u00e3o do trecho Norte da BR-163, que poder\u00e3o iniciar j\u00e1 no primeiro semestre de 2023, caso a MT Par assuma a concess\u00e3o da rodovia. Para isso, o Estado ainda depende da renegocia\u00e7\u00e3o de d\u00edvidas de financiamento contra\u00eddas para a primeira fase da duplica\u00e7\u00e3o, que s\u00e3o absorvidas com a troca do controle acion\u00e1rio. Ap\u00f3s, a previs\u00e3o \u00e9 que seja investido R$ 1,2 bilh\u00e3o de recursos pr\u00f3prios para a continua\u00e7\u00e3o da obra.<\/p>\n<p>O prefeito de Nova Mutum, Leandro Felix, tamb\u00e9m refor\u00e7ou a import\u00e2ncia da assinatura do TAC, principalmente para a seguran\u00e7a dos moradores locais.\u00a0 \u201cFicamos muito satisfeitos com essa a\u00e7\u00e3o diversificada do Governo do Estado, porque s\u00f3 quem percorre aquele caminho todos os dias e presencia tantos acidentes sabe a dificuldade que passamos, principalmente ao absorv\u00ea-los em nosso hospital. Agora surge a esperan\u00e7a de que essas obras ser\u00e3o concretizadas, e de que, no m\u00e1ximo em 8 anos, teremos a nossa rodovia duplicada e revitalizada\u201d, afirmou.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Lucas do Rio Verde, Miguel Vaz, disse que a decis\u00e3o do governo<\/p>\n","protected":false},"author":0,"featured_media":93157,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-93156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93156"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93157"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}