{"id":93146,"date":"2022-10-07T16:08:25","date_gmt":"2022-10-07T19:08:25","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/os-astros-e-estrelas-mais-legais-e-queridos-de-hollywood-2\/"},"modified":"2022-10-07T16:08:25","modified_gmt":"2022-10-07T19:08:25","slug":"os-astros-e-estrelas-mais-legais-e-queridos-de-hollywood-2","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/os-astros-e-estrelas-mais-legais-e-queridos-de-hollywood-2\/","title":{"rendered":"Os astros e estrelas mais legais e queridos de Hollywood"},"content":{"rendered":"<p>Alguns atores de Hollywood s\u00e3o acusados de serem inacess\u00edveis. Eles deixam sua riqueza e fama subirem \u00e0 cabe\u00e7a e esnobam os f\u00e3s que pedem selfies e aut\u00f3grafos. Felizmente, no entanto, nem toda celebridade \u00e9 assim. Aqui est\u00e3o algumas das exce\u00e7\u00f5es. Alguns s\u00e3o super legais com seus f\u00e3s, outros fazem o bem para o mundo em geral, ou \u00e0s vezes as duas coisas!<\/p>\n<p>Clique nesta galeria para descobrir mais sobre as celebridades mais legais que Hollywood tem a oferecer!<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/1952581\/os-astros-e-estrelas-mais-legais-e-queridos-de-hollywood?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alguns atores de Hollywood s\u00e3o acusados de serem inacess\u00edveis. Eles deixam sua riqueza e fama<\/p>\n","protected":false},"author":0,"featured_media":93147,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-93146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93146"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93147"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}