{"id":93144,"date":"2022-10-07T16:08:14","date_gmt":"2022-10-07T19:08:14","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/tce-conclui-primeira-etapa-do-programa-para-planejamento-estrategico-em-95-prefeituras\/"},"modified":"2022-10-07T16:08:14","modified_gmt":"2022-10-07T19:08:14","slug":"tce-conclui-primeira-etapa-do-programa-para-planejamento-estrategico-em-95-prefeituras","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/tce-conclui-primeira-etapa-do-programa-para-planejamento-estrategico-em-95-prefeituras\/","title":{"rendered":"TCE conclui primeira etapa do programa para planejamento estrat\u00e9gico em 95 prefeituras"},"content":{"rendered":"<p>O Tribunal de Contas de Mato Grosso concluiu o terceiro workshop do Programa de Gerenciamento do Planejamento Estrat\u00e9gico cumprindo mais uma meta da gest\u00e3o do presidente Jos\u00e9 Carlos Novelli.\u00a0 95 munic\u00edpios j\u00e1 aderiram e todos os gestores em primeiro mandato iniciaram os procedimentos.<\/p>\n<p>O supervisor da Escola Superior de Contas, conselheiro Waldir Teis, destacou que a meta j\u00e1 cumprida foi estabelecida justamente no planejamento estrat\u00e9gico do TCE para 2022, ferramenta que norteia uma gest\u00e3o. \u201cO presidente Novelli tem dito que o tribunal deve se voltar aos munic\u00edpios para apoi\u00e1-los no que for necess\u00e1rio e \u00fatil. O planejamento \u00e9 uma ferramenta que vai determinar o rumo que o munic\u00edpio vai tomar daqui para frente. N\u00e3o \u00e9 mais uma op\u00e7\u00e3o, \u00e9 uma obriga\u00e7\u00e3o\u201d, ressaltou.<\/p>\n<p>A nova lei de licita\u00e7\u00f5es trata do planejamento como princ\u00edpio b\u00e1sico da administra\u00e7\u00e3o p\u00fablica e o TCE est\u00e1 fazendo com os munic\u00edpios \u00e9 definir uma rotina, uma cultura do planejamento, pois a falta de um bom planejamento acarreta insufici\u00eancia e inefici\u00eancia.<\/p>\n<p>A primeira etapa do programa foi para capacitar e fornecer suporte para o planejamento estrat\u00e9gico dos gestores em primeiro mandato dos munic\u00edpios. O tribunal considera que \u00e9 imposs\u00edvel uma organiza\u00e7\u00e3o evoluir sem planejamento estrat\u00e9gico bem executado. Um munic\u00edpio, que gerencia milh\u00f5es em recursos, observando v\u00e1rias esferas da gest\u00e3o p\u00fablica, n\u00e3o evolui se n\u00e3o tiver estrutura de planejamento.<\/p>\n<p>D\u00e9bora Pedrotti, que \u00e9 coordenadora do conv\u00eanio com a Universidade Federal de Mato Grosso (UFMT), parceira do tribunal, tamb\u00e9m salientou que o planejamento \u00e9 importante para qualquer \u00e1rea, mas na administra\u00e7\u00e3o p\u00fablica \u00e9 essencial. \u201cPenso que n\u00e3o temos outra sa\u00edda que n\u00e3o seja o planejamento e aqui podemos experimentar as a\u00e7\u00f5es de ensino e extens\u00e3o junto com o Tribunal de Contas, por isso ficamos muito agradecidos\u201d, declarou, atrav\u00e9s da assessoria.<\/p>\n<p>O prefeito de Poxor\u00e9u, Nelson Paim, ressaltou sua satisfa\u00e7\u00e3o em ter assinado a ades\u00e3o ao Programa. \u201cQuando o Tribunal oferece essa proposta, isso \u00e9 de suma import\u00e2ncia. Vou colocar equipe e secret\u00e1rios para acompanhar e vamos fazer com que haja o retorno esperado tanto para o TCE quanto para n\u00f3s\u201d.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Contas de Mato Grosso concluiu o terceiro workshop do Programa de Gerenciamento<\/p>\n","protected":false},"author":0,"featured_media":93145,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-93144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93144"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93145"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}