{"id":93141,"date":"2022-10-07T15:17:34","date_gmt":"2022-10-07T18:17:34","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=93141"},"modified":"2022-10-07T15:17:35","modified_gmt":"2022-10-07T18:17:35","slug":"deputados-vao-estudar-desbolsonarizar-e-financiar-campanha","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/07\/deputados-vao-estudar-desbolsonarizar-e-financiar-campanha\/","title":{"rendered":"Deputados v\u00e3o &#8216;estudar&#8217;, &#8216;desbolsonarizar&#8217; e financiar campanha"},"content":{"rendered":"\n<p>A campanha do presidente Jair Bolsonaro (PL) pediu para que os deputados bolsonaristas eleitos se &#8216;desbolsonarizem&#8217; e estudem o governo para defender a gest\u00e3o e tentar conquistar votos neste 2\u00ba turno em Mato Grosso. A orienta\u00e7\u00e3o foi dada durante o encontro do presidente com os deputados e senadores eleitos de todo o pa\u00eds e que apoiaram Bolsonaro nestas elei\u00e7\u00f5es. &nbsp;<\/p>\n\n\n\n<p>De acordo com a estrat\u00e9gia de campanha, os deputados federais eleitos de Mato Grosso, dever\u00e3o dividir o Estado em regi\u00f5es para que eles passem o 2\u00ba turno fazendo campanha.\u00a0 A &#8216;desbolsonariza\u00e7\u00e3o&#8217; pedida pela campanha, \u00e9 para que os bolsonaristas parem de atacar as urnas e o sistema eleitoral, assim como PT e o ex-presidente Lula (PT), e foquem nas a\u00e7\u00f5es da gest\u00e3o Bolsonaro. \u00a0<\/p>\n\n\n\n<p>&#8220;N\u00e3o vamos falar de urnas, do PT e Lula. Vamos falar do nosso governo, do que fizemos. Por isso pe\u00e7o que todos voc\u00eas leem os materais que vamos passar&#8221;, disse um dos membros da c\u00fapula de campanha durante a reuni\u00e3o.<\/p>\n\n\n\n<p>Outro pedido \u00e9 para que os pr\u00f3prios deputados e senadores no Estado, arquem com os materiais de campanha, e se poss\u00edvel, que mantenham a estrutura de suas campanhas com cabos eleitorais at\u00e9 o dia 30 de outubro, quando ocorre a vota\u00e7\u00e3o do 2\u00ba turno. &nbsp;<\/p>\n\n\n\n<p>Os parlamentares eleitos em Mato Grosso, devem pedir doa\u00e7\u00f5es do agroneg\u00f3cio, para confeccionarem os materiais de campanha de Bolsonaro. Por\u00e9m, a pr\u00e1tica poder\u00e1 ser caracterizada crime eleitoral de caixa 2, j\u00e1 que todo e qualquer material de campanha para distribui\u00e7\u00e3o devem ser contabilizados dentro do caixa oficial de campanha. &nbsp;<\/p>\n\n\n\n<p>As orienta\u00e7\u00f5es passadas por alguns parlamentares eleitos \u00e0 sua base eleitoral, principalmente no que diz respeito a capta\u00e7\u00e3o de recursos atrav\u00e9s de &#8216;vakinhas&#8217; e doa\u00e7\u00f5es do agroneg\u00f3cio. \u00a0<\/p>\n\n\n\n<p>Caso as doa\u00e7\u00f5es n\u00e3o sejam repassadas ao caixa de campanha oficial, ou se a confecc\u00e7\u00e3o de materiais sejam feitas pelos pr\u00f3prios deputados no Estado, a Justi\u00e7a Eleitoral poder\u00e1 ser acionada e os materiais apreendidos, conforme a legisla\u00e7\u00e3o eleitoral.<\/p>\n\n\n\n<p><strong><em>Por Pablo Rodrigo<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A campanha do presidente Jair Bolsonaro (PL) pediu para que os deputados bolsonaristas eleitos se<\/p>\n","protected":false},"author":2,"featured_media":93142,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-93141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93141"}],"version-history":[{"count":1,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93141\/revisions"}],"predecessor-version":[{"id":93143,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93141\/revisions\/93143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93142"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}