{"id":93019,"date":"2022-10-06T17:08:21","date_gmt":"2022-10-06T20:08:21","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/06\/jogador-de-handebol-assume-homossexualidade-e-mostra-namorado\/"},"modified":"2022-10-06T17:08:21","modified_gmt":"2022-10-06T20:08:21","slug":"jogador-de-handebol-assume-homossexualidade-e-mostra-namorado","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/06\/jogador-de-handebol-assume-homossexualidade-e-mostra-namorado\/","title":{"rendered":"Jogador de handebol assume homossexualidade e mostra namorado"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL-FOLHAPRESS) &#8211; O jogador alem\u00e3o de handebol Lucas Krzikalla, 28 anos, assumiu ser homossexual e se tornou o primeiro atleta de uma equipe a revelar que \u00e9 gay em uma das quatro principais ligas profissionais da Alemanha.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Krzikalla fez o an\u00fancio em entrevista ao jornal alem\u00e3o Welt Am Sonntag e recebeu muitas mensagens de apoio.<br \/>&#8220;Estou feliz, muito animado e livre. N\u00e3o esperava tanto incentivo&#8221;, disse ao jornal.<\/p>\n<p>\u00a0<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CjKSjQ2IusD\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div>\n<div>\n<div><\/div>\n<div>\n<div><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<div>Ver esta publica\u00e7\u00e3o no Instagram<\/div>\n<\/div>\n<p><a href=\"https:\/\/www.instagram.com\/p\/CjKSjQ2IusD\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Uma publica\u00e7\u00e3o partilhada por Lucas Krzikalla (@lucaskrzikalla)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p>O SC DHfK Leipzig, clube do atleta, divulgou um novo card do jogador, com o nome dele e o n\u00famero da camisa pintados com as cores do arco-\u00edris.<\/p>\n<p>&#8220;Uma amiga me disse que um garoto de seu c\u00edrculo de amigos se assumiu para sua fam\u00edlia depois que leu sobre o meu an\u00fancio&#8221;, disse o atleta.<\/p>\n<p>Ap\u00f3s se assumir homossexual, Krzikalla postou uma foto com seu namorado, Chris Gross. Ele colocou um emoji de cora\u00e7\u00e3o na legenda da publica\u00e7\u00e3o.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1952539\/jogador-de-handebol-assume-homossexualidade-e-mostra-namorado?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL-FOLHAPRESS) &#8211; O jogador alem\u00e3o de handebol Lucas Krzikalla, 28 anos, assumiu<\/p>\n","protected":false},"author":0,"featured_media":93020,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-93019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93019"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93020"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}