{"id":93017,"date":"2022-10-06T17:08:18","date_gmt":"2022-10-06T20:08:18","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/06\/gio-ewbank-diz-que-foi-assediada-por-ator-consagrado-da-globo-em-a-favorita\/"},"modified":"2022-10-06T17:08:18","modified_gmt":"2022-10-06T20:08:18","slug":"gio-ewbank-diz-que-foi-assediada-por-ator-consagrado-da-globo-em-a-favorita","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/06\/gio-ewbank-diz-que-foi-assediada-por-ator-consagrado-da-globo-em-a-favorita\/","title":{"rendered":"Gio Ewbank diz que foi assediada por ator consagrado da Globo em &#8216;A Favorita&#8217;"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; No ano de 2008, a atriz Giovanna Ewbank, 36, fazia apenas o seu segundo trabalho na Globo, na pele de Sharon, uma garota de programa que trabalhava em uma ag\u00eancia. Por conta disso, o figurino quase sempre era mais sensual do que o das outras personagens. E foi justamente num dia em que ela vestia uma roupa mais curta que conta ter sofrido um ass\u00e9dio dentro da Globo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Lembro que estava andando no corredor para ir gravar e tinha um ator consagrad\u00edssimo, mais velho, com uma super carreira. Estava com um short curt\u00edssimo, [ele] foi l\u00e1, me deu um tap\u00e3o na bunda no corredor na frente de todo mundo e falou: &#8216;T\u00e1 boa, hein?&#8217;. Imediatamente fui para o camarim e comecei a chorar&#8221;, lembrou ela em papo com Fernanda Paes Leme e Deborah Secco no podcast Quem Pode, Pod.<\/p>\n<p>Sem saber como lidar com a situa\u00e7\u00e3o na ocasi\u00e3o, Ewbank diz ter perguntado para algumas colegas de elenco sobre que medida ela deveria tomar, mas que foi desencorajada a contar para a chefia. &#8220;&#8216;Cara, n\u00e3o faz nada! Ele \u00e9 muito fod* e voc\u00ea vai se dar mal'&#8221;, teriam dito as colegas.<\/p>\n<p>A atriz e apresentadora explica que se essa situa\u00e7\u00e3o tivesse acontecido nos dias de hoje tudo seria diferente. &#8220;Na \u00e9poca eu n\u00e3o achava que era ass\u00e9dio. Senti um desconforto, mas [disse:] &#8216;Ah n\u00e3o, n\u00e3o \u00e9 ass\u00e9dio'&#8221;, concluiu Ewbank.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1952502\/gio-ewbank-diz-que-foi-assediada-por-ator-consagrado-da-globo-em-a-favorita?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; No ano de 2008, a atriz Giovanna Ewbank, 36, fazia<\/p>\n","protected":false},"author":0,"featured_media":93018,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-93017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=93017"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/93017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/93018"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=93017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=93017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=93017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}