{"id":92880,"date":"2022-10-05T19:08:26","date_gmt":"2022-10-05T22:08:26","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/05\/gloria-perez-e-elenco-evitam-politica-em-festa-de-travessia\/"},"modified":"2022-10-05T19:08:26","modified_gmt":"2022-10-05T22:08:26","slug":"gloria-perez-e-elenco-evitam-politica-em-festa-de-travessia","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/05\/gloria-perez-e-elenco-evitam-politica-em-festa-de-travessia\/","title":{"rendered":"Gl\u00f3ria Perez e elenco evitam pol\u00edtica em festa de &#8216;Travessia&#8217;"},"content":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; A cinco dias de estreia de sua 15\u00aa novela, Gl\u00f3ria Perez bem que tentou s\u00f3 falar sobre &#8220;Travessia&#8221; na noite de lan\u00e7amento da produ\u00e7\u00e3o, nesta ter\u00e7a-feira (4), mas n\u00e3o deu. A pol\u00eamica curtida em defesa do voto para Jair Bolsonaro (PL) \u00e0s v\u00e9speras do primeiro turno das elei\u00e7\u00f5es 2022, ainda ronda a autora da pr\u00f3xima trama das 21h da Globo.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Gl\u00f3ria, 73, assumiu que n\u00e3o foi um erro. &#8220;Curti. Eu curti, sim, e esse patrulhamento de likes \u00e9 muito chato. Pelo amor de Deus! Vamos parar com isso. Sinceramente, n\u00e3o acho que deva ser um problema ficar comentando [curtir publica\u00e7\u00f5es] ou n\u00e3o esse tipo de coisa&#8221;, disse a autora, que n\u00e3o quis falar sobre o segundo turno. &#8220;Tenho que cumprimentar os atores&#8221;, anunciou.<\/p>\n<p>Mas antes de deixar a rodinha de jornalistas, Gl\u00f3ria reconheceu que estrear &#8220;Travessia&#8221; em um momento que as aten\u00e7\u00f5es se voltam para outros assuntos \u00e9 um desafio. &#8220;Acredito que neste momento, as pessoas est\u00e3o mais interessadas na pol\u00edtica do que assistir uma novela. \u00c9 um desafio e ele se torna ainda maior porque logo depois temos uma Copa do Mundo de futebol&#8221;.<\/p>\n<p>Al\u00e9m da autora de &#8220;Travessia&#8221;, que estreia dia 10, Alessandra Negrini, Alexandre Nero, Jade Picon e Grazi Massafera preferiram n\u00e3o opinar sobre o resultado das urnas. &#8220;Viemos aqui para falar da novela. N\u00f3s j\u00e1 estamos t\u00e3o polarizados, n\u00e3o vamos misturar tudo&#8221;, disse Grazi, uma das muitas celebridades que declararam voto em Lula antes das elei\u00e7\u00f5es. A atriz participa apenas dos primeiros cap\u00edtulos da trama, como m\u00e3e de Chiara, personagem de Jade Picon.<\/p>\n<p>Negrini tamb\u00e9m preferiu n\u00e3o se aprofundar sobre o assunto, bastante abordado por ela em suas redes. &#8220;Acho melhor n\u00e3o ficar falando muito disso agora porque a gente est\u00e1 aqui para falar da novela&#8221;, respondeu, ao ser perguntada se havia ficado surpresa com o resultado das urnas.<\/p>\n<p>De todo o elenco, quem mais se estendeu ao falar sobre pol\u00edtica (e religi\u00e3o) foi C\u00e1ssia Kis, que confirmou o que vinha sendo especulado: est\u00e1 com Bolsonaro e n\u00e3o abre. &#8220;Ele \u00e9 o \u00fanico presidente do mundo que fala em Deus. E fala com for\u00e7a&#8221;, disse a atriz, que h\u00e1 dois anos fez duras cr\u00edticas ao capit\u00e3o: &#8220;Ele deveria tomar uma surra de cinto da m\u00e3e dele&#8221;, disse, \u00e0 \u00e9poca.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1952238\/gloria-perez-e-elenco-evitam-politica-em-festa-de-travessia?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; A cinco dias de estreia de sua 15\u00aa novela,<\/p>\n","protected":false},"author":0,"featured_media":92881,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-92880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92880"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92881"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}