{"id":92870,"date":"2022-10-05T18:08:17","date_gmt":"2022-10-05T21:08:17","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/05\/mais-que-amigos-e-comedia-romantica-que-quer-estourar-a-bolha-lgbt\/"},"modified":"2022-10-05T18:08:17","modified_gmt":"2022-10-05T21:08:17","slug":"mais-que-amigos-e-comedia-romantica-que-quer-estourar-a-bolha-lgbt","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/05\/mais-que-amigos-e-comedia-romantica-que-quer-estourar-a-bolha-lgbt\/","title":{"rendered":"&#8216;Mais que Amigos&#8217; \u00e9 com\u00e9dia rom\u00e2ntica que quer estourar a bolha LGBT"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Com\u00e9dias rom\u00e2nticas s\u00e3o formativas para muita gente. Declara\u00e7\u00f5es, festas de casamento e palavras apaixonadas dos filmes com frequ\u00eancia inspiram casais na vida real. Para quem \u00e9 LGBTQIA+, no entanto, o acervo de refer\u00eancias \u00e9 bastante escasso.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>\u00c9 por isso que &#8220;Mais que Amigos&#8221;, que chega aos cinemas nesta semana, vem sendo tratado com alarde n\u00e3o s\u00f3 por seu est\u00fadio, mas tamb\u00e9m pelo p\u00fablico e a m\u00eddia -ganhou at\u00e9 exibi\u00e7\u00e3o especial no Festival de Toronto, sob o t\u00edtulo de primeira grande com\u00e9dia rom\u00e2ntica sobre dois homens.<\/p>\n<p>&#8220;O r\u00f3tulo \u00e9 importante, n\u00f3s n\u00e3o devemos ficar t\u00edmidos em rela\u00e7\u00e3o a ele. N\u00f3s tivemos muitos filmes do g\u00eanero sobre heterossexuais, que nos fizeram rir e chorar, \u00e9 verdade, mas nunca algo assim&#8221;, diz Billy Eichner, protagonista, roteirista e produtor.<\/p>\n<p>&#8220;Uma coisa que eu tenho em comum com o meu personagem \u00e9 o fato de ser escancaradamente gay. Eu estive fora do arm\u00e1rio desde muito cedo na minha carreira, mas levou muito tempo para Hollywood celebrar isso, para achar legal. Agora \u00e9 a minha oportunidade de mostrar n\u00e3o s\u00f3 qu\u00e3o divertidos, mas tamb\u00e9m complicados e multidimensionais personagens LGBTQIA+ podem ser.&#8221;<\/p>\n<p>N\u00e3o \u00e9 exatamente verdade, no entanto, que &#8220;Mais que Amigos&#8221; seja a primeira com\u00e9dia rom\u00e2ntica homossexual de um grande est\u00fadio. Neste ano, a Searchlight Pictures lan\u00e7ou &#8220;Fire Island: Orgulho e Sedu\u00e7\u00e3o&#8221; e, no retrasado, a TriStar Pictures, da Sony, bancou &#8220;Algu\u00e9m Avisa?&#8221;, um Natal l\u00e9sbico estrelado por Kristen Stewart.<\/p>\n<p>O marketing em torno da ideia de ser o primeiro pegou mal nas redes sociais, \u00e0s quais Eichner j\u00e1 recorreu para se explicar. &#8220;Mais que Amigos&#8221; n\u00e3o \u00e9 uma trag\u00e9dia ou uma produ\u00e7\u00e3o independente -onde est\u00e1 a vanguarda da diversidade sexual e de g\u00eanero-, ele diz agora, e sua escala e a aten\u00e7\u00e3o que a Universal tem dado ao filme s\u00e3o o que sustentam o ineditismo.<\/p>\n<p>&#8220;Fire Island&#8221; e &#8220;Algu\u00e9m Avisa?&#8221;, \u00e9 verdade, n\u00e3o receberam o mesmo prest\u00edgio em seus lan\u00e7amentos e foram direto para o streaming. &#8220;Mais que Amigos&#8221;, portanto, tem a miss\u00e3o de provar o apelo de seu romance gay nas dif\u00edceis bilheterias p\u00f3s-Covid.<\/p>\n<p>No novo filme, Eichner d\u00e1 vida a um apresentador de podcast que se acha imune \u00e0 paix\u00e3o. Ele divide seu tempo entre gravar seu programa, escrever livros infantis queer e buscar homens com quem transar no Grindr, aplicativo de pega\u00e7\u00e3o que testa sua paci\u00eancia com pedidos constantes por fotos \u00edntimas -ele eventualmente cede, mas corta o bumbum com uma l\u00e2mina de barbear enquanto a prepara para o ensaio fotogr\u00e1fico.<\/p>\n<p>At\u00e9 que sua vida come\u00e7a a ganhar um prop\u00f3sito maior, quando ele \u00e9 convidado para coordenar o que seria o primeiro museu de hist\u00f3ria LGBTQIA+ dos Estados Unidos, em Nova York, e quando encontra um rapaz igualmente avesso a compromissos, mas com quem sente uma conex\u00e3o instant\u00e2nea.<\/p>\n<p>O papel \u00e9 de Luke Macfarlane, fort\u00e3o que, ao contr\u00e1rio de Eichner, teve mais dificuldade para se conciliar com a homossexualidade, tendo que ouvir de agentes e colegas de profiss\u00e3o que jamais estrelaria um filme de a\u00e7\u00e3o se sa\u00edsse do arm\u00e1rio. Ele n\u00e3o se importou, mas ainda espera pelo papel.<\/p>\n<p>Se n\u00e3o tivesse se assumido, no entanto, Macfarlane teria passado longe de &#8220;Mais que Amigos&#8221;, no entanto. O longa decidiu escalar s\u00f3 atores LGBTQIA+ -e n\u00e3o s\u00f3 para os pap\u00e9is queer. Aqui, eles d\u00e3o vida tamb\u00e9m aos personagens heterossexuais, numa esp\u00e9cie de subvers\u00e3o pela qual Eichner fez quest\u00e3o de brigar.<\/p>\n<p>Foi uma decis\u00e3o carregada de mensagem em meio a discuss\u00f5es infind\u00e1veis que surgem aos montes na internet sempre que algum h\u00e9tero \u00e9 escolhido para um papel gay, como foi com Michael Cimino na s\u00e9rie &#8220;Com Amor, Victor&#8221; ou com Harry Styles, que n\u00e3o quer se rotular, no filme &#8220;My Policeman&#8221;.<\/p>\n<p>Nicholas Stoller, o diretor de &#8220;Mais que Amigos&#8221;, foi curiosamente um dos poucos heterossexuais no set de filmagem. Mas Eichner o queria pela experi\u00eancia em com\u00e9dias como &#8220;Ressaca de Amor&#8221; e &#8220;Cinco Anos de Noivado&#8221;, e o cineasta conta que tomou para si a miss\u00e3o de desenvolver o filme de forma colaborativa, ouvindo as hist\u00f3rias pessoais e opini\u00f5es daqueles ao redor.<\/p>\n<p>&#8220;Quando o assunto \u00e9 humor, voc\u00ea precisa sempre buscar uma novidade. \u00c9 natural, ent\u00e3o, que o g\u00eanero hoje esteja indo em dire\u00e7\u00e3o a novos tipos de personagem. \u00c9 um movimento natural e que me anima, e eu ficava intrigado de ser f\u00e3 de com\u00e9dias rom\u00e2nticas e nunca ter visto uma gay na telona&#8221;, diz.<\/p>\n<p>O fato de Stoller n\u00e3o ser gay, ali\u00e1s, ajuda a romper com a ideia de que &#8220;Mais que Amigos&#8221; \u00e9 uma trama de nicho, que s\u00f3 homossexuais v\u00e3o querer ver. \u00c9 verdade que o filme \u00e9 recheado de refer\u00eancias que s\u00f3 os LGBTQIA+ v\u00e3o entender -dos musicais de teatro \u00e0s divas pop, das boates ao sexo, bastante presente. Mas ele diz que h\u00e1 piadas para todos e o quanto mais espec\u00edfica \u00e9 uma hist\u00f3ria, mais universal seus temas principais se tornam.<br \/>&#8220;A ideia de nicho est\u00e1 nos olhos de quem v\u00ea. Por que as minhas refer\u00eancias enquanto homem gay s\u00e3o nichadas e n\u00e3o as de um homem h\u00e9tero?&#8221;, questiona Eichner, em seguida. &#8220;Para mim, o Super Bowl, ent\u00e3o, \u00e9 nichado. Que o espectador estranhe essas especificidades pode ser algo bom. \u00c9 uma com\u00e9dia rom\u00e2ntica diferente, mas as emo\u00e7\u00f5es s\u00e3o as mesmas.&#8221;<\/p>\n<\/p>\n<p><span class=\"news_bold\">MAIS QUE AMIGOS<\/span><\/p>\n<p>Quando Estreia nesta quinta (6), nos cinemas<br \/>Classifica\u00e7\u00e3o 16 anos<br \/>Elenco Billy Eichner, Luke Macfarlane e Dot-Marie Jones<br \/>Produ\u00e7\u00e3o EUA, 2022<br \/>Dire\u00e7\u00e3o Nicholas Stoller<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Cultura<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/ultima-hora\/1952220\/mais-que-amigos-e-comedia-romantica-para-gays-que-quer-estourar-a-bolha-lgbt?utm_source=rss-cultura&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; Com\u00e9dias rom\u00e2nticas s\u00e3o formativas para muita gente. Declara\u00e7\u00f5es, festas de<\/p>\n","protected":false},"author":0,"featured_media":92871,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-92870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92870"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92871"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}