{"id":92820,"date":"2022-10-05T13:08:03","date_gmt":"2022-10-05T16:08:03","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/05\/prefeitura-vai-destinar-mais-de-r-200-mil-para-iluminar-area-de-lago-em-nova-mutum\/"},"modified":"2022-10-05T13:08:03","modified_gmt":"2022-10-05T16:08:03","slug":"prefeitura-vai-destinar-mais-de-r-200-mil-para-iluminar-area-de-lago-em-nova-mutum","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/05\/prefeitura-vai-destinar-mais-de-r-200-mil-para-iluminar-area-de-lago-em-nova-mutum\/","title":{"rendered":"Prefeitura vai destinar mais de R$ 200 mil para iluminar \u00e1rea de lago em Nova Mutum"},"content":{"rendered":"<p>A prefeitura informou, em publica\u00e7\u00e3o oficial no portal da transpar\u00eancia, que deve licitar, na modalidade de tomada de pre\u00e7os, para entrega e instala\u00e7\u00e3o de sistemas de ilumina\u00e7\u00e3o submersos, bem como elementos decorativos no Lago do Semeador, na avenida Mutum, na regi\u00e3o central. Os servi\u00e7os t\u00eam como objetivo transformar o local num ponto tur\u00edstico e de lazer regular para moradores.<\/p>\n<p>Ser\u00e3o fornecidas duas plataformas para o funcionamento de fontes flutuantes, 14 unidades de bico vulc\u00e2nico, 36 projetores de luz subaqu\u00e1ticos em LED, al\u00e9m de bombas submers\u00edveis, pain\u00e9is de controle eletr\u00f4nico monof\u00e1sicos, cabos blindados, eletrodutos e conex\u00f5es em PVC para o funcionamento adequado dos equipamentos.<\/p>\n<p>O edital est\u00e1 programado para 21 de outubro, com or\u00e7amento de R$ 243 mil. Toda a aparelhagem tamb\u00e9m deve auxiliar \u201cem e\u0301poca de estiagem, onde o fuxo de a\u0301gua dentro do lago diminui drasticamente. Os jatos de a\u0301gua lanc\u0327ados sera\u0303o de grande ajuda na oxigenac\u0327a\u0303o da a\u0301gua, atuando na manuten\u00e7\u00e3o da fauna e flora do ambiente\u201d, de acordo com a prefeitura.<\/p>\n<p>Os trabalhos devem ser conclu\u00eddos em at\u00e9 60 dias, conforme o cronograma f\u00edsico-financeiro.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prefeitura informou, em publica\u00e7\u00e3o oficial no portal da transpar\u00eancia, que deve licitar, na modalidade<\/p>\n","protected":false},"author":0,"featured_media":92821,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92820"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92821"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}