{"id":92700,"date":"2022-10-04T18:08:32","date_gmt":"2022-10-04T21:08:32","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/bia-haddad-estreia-com-vitoria-nas-duplas-no-torneio-de-ostrava\/"},"modified":"2022-10-04T18:08:32","modified_gmt":"2022-10-04T21:08:32","slug":"bia-haddad-estreia-com-vitoria-nas-duplas-no-torneio-de-ostrava","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/bia-haddad-estreia-com-vitoria-nas-duplas-no-torneio-de-ostrava\/","title":{"rendered":"Bia Haddad estreia com vit\u00f3ria nas duplas no Torneio de Ostrava"},"content":{"rendered":"<p>Beatriz Haddad Maia estreou com vit\u00f3ria no Torneio de Ostrava, na Rep\u00fablica Checa, nesta ter\u00e7a-feira. Bia venceu na chave de duplas ao lado da casaque Anna Danilina, parceira com quem pretende buscar a vaga no WTA Finals, no fim da temporada. Juntas, elas venceram a local Renata Voracova e a chinesa Wang Xiyu por 2 sets a 0, com parciais de 6\/2 e 6\/4, em 1h10min de confronto. <\/p>\n<p>Com a vit\u00f3ria, elas avan\u00e7aram \u00e0s quartas de final da competi\u00e7\u00e3o de n\u00edvel WTA 500. A dupla da brasileira vai enfrentar agora as locais Nikola Bartunkova e Barbora Palicova, que superaram a georgiana Natela Dzalamidze e a russa Alexandra Panova tamb\u00e9m por 2 a 0, com parciais de 7\/6 (7\/4) e 6\/4.<\/p>\n<\/p>\n<p>Bia e Danilina surpreenderam no in\u00edcio da temporada ao se sagrarem campe\u00e3s em Sydney e alcan\u00e7arem a final do Aberto da Austr\u00e1lia, num dos melhores resultados do t\u00eanis brasileiro feminino num torneio de Grand Slam. <\/p>\n<\/p>\n<p>Nesta reta final da temporada, elas buscam somar mais pontos para tentar assegurar uma vaga no WTA Finals, torneio que re\u00fane as oito melhores tenistas e as oito melhores duplas do ano. No momento, brasileira e casaque ocupam o 10\u00ba lugar do ranking do ano.<\/p>\n<\/p>\n<p>LUISA STEFANI<\/p>\n<p>A medalhista de bronze na Olimp\u00edada de T\u00f3quio jogou sua primeira partida de simples desde seu retorno \u00e0s quadras, no m\u00eas passado. E ela foi eliminada no qualifying do ITF W80 de Rancho Santa Fe, nos Estados Unidos. Ainda nesta ter\u00e7a, estrear\u00e1 na chave de duplas, ao lado da australiana Ellen Perez.<\/p>\n<\/p>\n<p>FAVORITOS DECEPCIONAM<\/p>\n<p>O espanhol Carlos Alcaraz e o noruegu\u00eas Casper Ruud, atuais n\u00famero 1 e 3 do mundo, decepcionaram nesta ter\u00e7a. Ambos foram eliminados logo na estreia em diferentes torneios. Em Astana, no Casaquist\u00e3o, o l\u00edder do ranking foi derrotado pelo belga David Goffin por 7\/5 e 6\/3. Em T\u00f3quio, Ruud n\u00e3o resistiu ao espanhol Jaume Munar e levou um duplo 6\/3.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1951804\/bia-haddad-estreia-com-vitoria-nas-duplas-no-torneio-de-ostrava?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beatriz Haddad Maia estreou com vit\u00f3ria no Torneio de Ostrava, na Rep\u00fablica Checa, nesta ter\u00e7a-feira.<\/p>\n","protected":false},"author":0,"featured_media":92701,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-92700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92700"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92701"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}