{"id":92673,"date":"2022-10-04T16:08:18","date_gmt":"2022-10-04T19:08:18","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/meghan-e-harry-buscam-casa-mas-moradores-nao-os-querem-como-vizinhos-diz-site\/"},"modified":"2022-10-04T16:08:18","modified_gmt":"2022-10-04T19:08:18","slug":"meghan-e-harry-buscam-casa-mas-moradores-nao-os-querem-como-vizinhos-diz-site","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/meghan-e-harry-buscam-casa-mas-moradores-nao-os-querem-como-vizinhos-diz-site\/","title":{"rendered":"Meghan e Harry buscam casa, mas moradores n\u00e3o os querem como vizinhos, diz site"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O casal Meghan Markle, 41, e pr\u00edncipe Harry, 38, busca por uma nova casa na comunidade Hope Ranch, em Santa B\u00e1rbara, nos Estados Unidos, como reporta o Daily Mail. A ideia deles \u00e9 morar num local maior j\u00e1 que agora, com dois filhos, a resid\u00eancia em Montecito, na Calif\u00f3rnia, com valor de mais de R$ 70 milh\u00f5es, tem ficado pequena com a chegada de Lilibet.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Por\u00e9m, de acordo com o TMZ, vizinhos dessa localidade n\u00e3o querem receber os novos moradores. Eles temem que a regi\u00e3o, bastante pacata, comece a borbulhar com fot\u00f3grafos, carros e todos os holofotes que eles trazem na bagagem.<\/p>\n<p>Fontes do site afirmam que o bairro \u00e9 bastante privado e que a chegada do duque e da duquesa trariam um verdadeiro &#8220;circo&#8221; para as redondezas. Por haver ruas estreitas e sinuosas, muita gente teme que o ac\u00famulo de carros possa prejudicar as crian\u00e7as que costumam brincar nas ruas e sair das escolas do bairro.<\/p>\n<p>Ap\u00f3s diversos desentendimentos, os dois foram oficialmente &#8220;rebaixados&#8221; no site oficial da fam\u00edlia real brit\u00e2nica. Agora, as fotos do duque e duquesa de Sussex aparecerem no final da lista.<br \/>Harry e Meghan est\u00e3o acima apenas do pr\u00edncipe Andrew, 62, filho da rainha Elizabeth 2\u00aa (1926-2022) envolvido em caso de abuso sexual e afastado da coroa brit\u00e2nica desde que fechou um acordo na Justi\u00e7a americana.<\/p>\n<p>Antes, a p\u00e1gina dedicadas ao casal estava posicionada abaixo das do pr\u00edncipe William, 40, e Kate Middleton, 40. Ap\u00f3s deixarem suas fun\u00e7\u00f5es em janeiro de 2020, as p\u00e1ginas dos dois foram reposicionadas abaixo da princesa Anne.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/celebridades\/1951827\/meghan-e-harry-buscam-casa-mas-moradores-nao-os-querem-como-vizinhos-diz-site?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; O casal Meghan Markle, 41, e pr\u00edncipe Harry, 38, busca<\/p>\n","protected":false},"author":0,"featured_media":92674,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-92673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92673"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92674"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}