{"id":92667,"date":"2022-10-04T15:08:26","date_gmt":"2022-10-04T18:08:26","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/cristiano-ronaldo-pode-deixar-o-manchester-united-em-janeiro-diz-jornal\/"},"modified":"2022-10-04T15:08:26","modified_gmt":"2022-10-04T18:08:26","slug":"cristiano-ronaldo-pode-deixar-o-manchester-united-em-janeiro-diz-jornal","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/cristiano-ronaldo-pode-deixar-o-manchester-united-em-janeiro-diz-jornal\/","title":{"rendered":"Cristiano Ronaldo pode deixar o Manchester United em janeiro, diz jornal"},"content":{"rendered":"<p>Cristiano Ronaldo pode estar vivendo seus \u00faltimos momentos com a camisa do Manchester United. Com poucas oportunidades no time titular, o jogador pode deixar a equipe em janeiro, quando abre a janela de transfer\u00eancias do meio da temporada do futebol europeu. A informa\u00e7\u00e3o foi divulgada nesta ter\u00e7a-feira pelo jornal brit\u00e2nico <i>The Telegraph<\/i>.<\/p>\n<p>Segundo a publica\u00e7\u00e3o, o astro portugu\u00eas de 37 anos mant\u00e9m o desejo de deixar a equipe, que n\u00e3o se classificou para a disputa da Liga dos Campe\u00f5es deste ano &#8211; este ainda seria o principal motivo externado pelo craque. Por sua vez, o novo comandante do time de Manchester, o holand\u00eas Erik Ten Hag, teria deixado claro que &#8220;n\u00e3o ficaria no caminho&#8221; do atacante se uma boa proposta surgir.<\/p>\n<\/p>\n<p>Cristiano Ronaldo n\u00e3o saiu do banco de reservas no massacre por 6 a 3 sofrido para o rival Manchester City no fim de semana. Ao ser questionado por que n\u00e3o colocou o portugu\u00eas em campo mesmo precisando correr atr\u00e1s do resultado, Ten Hag explicou que n\u00e3o o fez em respeito pela sua &#8220;grande carreira&#8221;. O atleta manteve um semblante de decep\u00e7\u00e3o durante boa parte da partida. At\u00e9 o momento, acumula apenas 80 minutos no Campeonato Ingl\u00eas.<\/p>\n<\/p>\n<p>Apesar de ter comunicado o Manchester United do desejo de sair desde o fim da temporada passada, o jogador eleito por cinco vezes Melhor do Mundo n\u00e3o recebeu nenhuma proposta vantajosa na \u00faltima janela de transfer\u00eancias, encerrada no dia 1\u00ba de setembro. A \u00fanica oferta colocada na mesa foi do Al-Hilal, da Ar\u00e1bia Saudita, que prop\u00f4s cerca de R$ 162 milh\u00f5es ao clube brit\u00e2nico, al\u00e9m de outros R$ 108 milh\u00f5es a empres\u00e1rios, mas o neg\u00f3cio foi prontamente recusado pelo jogador, que embolsaria cerca de R$ 1,24 bilh\u00e3o.<\/p>\n<\/p>\n<p>Jorge Mendes, empres\u00e1rio do atleta, chegou a oferecer o atacante para o Real Madrid, clube em que o portugu\u00eas marcou \u00e9poca entre 2009 e 2018, mas recebeu um posicionamento negativo da diretoria merengue. At\u00e9 mesmo o Atl\u00e9tico de Madrid, um dos maiores rivais do time madrilenho e uma das maiores v\u00edtimas do portugu\u00eas, recusou o jogador.<\/p>\n<\/p>\n<p>Bayern de Munique, Chelsea e Paris Saint-Germain foram outros clubes procurados pelo agente de Cristiano, mas fecharam as suas portas para o astro por entender que o atleta n\u00e3o condiz atualmente com o estilo de jogo proposto pelas equipes, al\u00e9m da alta pedida salarial.<\/p>\n<\/p>\n<p>O Manchester United anunciou o retorno de Cristiano Ronaldo em agosto do ano passado. O clube ingl\u00eas teria desembolsado cerca de 20 milh\u00f5es de euros (R$ 122 milh\u00f5es) para tirar o jogador da Juventus. Pela equipe italiana, o portugu\u00eas atuou durante tr\u00eas temporadas, tendo conquistado dois t\u00edtulos do Campeonato Italiano, da Copa da It\u00e1lia e da Supercopa da It\u00e1lia.<\/p>\n<\/p>\n<p>Foi pelo Manchester United, na temporada 2007\/08, que Cristiano conquistou pela primeira vez o t\u00edtulo da Liga dos Campe\u00f5es da Europa e o pr\u00eamio de melhor jogador do mundo pela Fifa. No Real Madrid, o portugu\u00eas teve ainda mais sucesso internacional com mais quatro t\u00edtulos da Liga dos Campe\u00f5es e outras quatro elei\u00e7\u00f5es de melhor do mundo, entre 2013 e 2017, cravando seu nome entre os maiores da hist\u00f3ria do futebol.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1951821\/cristiano-ronaldo-pode-deixar-o-manchester-united-em-janeiro-diz-jornal?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristiano Ronaldo pode estar vivendo seus \u00faltimos momentos com a camisa do Manchester United. Com<\/p>\n","protected":false},"author":0,"featured_media":92668,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-92667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92667"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92668"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}