{"id":92657,"date":"2022-10-04T13:08:20","date_gmt":"2022-10-04T16:08:20","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/farmacias-devem-registrar-menos-de-mil-casos-de-covid-ainda-neste-mes\/"},"modified":"2022-10-04T13:08:20","modified_gmt":"2022-10-04T16:08:20","slug":"farmacias-devem-registrar-menos-de-mil-casos-de-covid-ainda-neste-mes","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/04\/farmacias-devem-registrar-menos-de-mil-casos-de-covid-ainda-neste-mes\/","title":{"rendered":"Farm\u00e1cias devem registrar menos de mil casos de Covid ainda neste m\u00eas"},"content":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; Os testes de Covid nas farm\u00e1cias se mantiveram abaixo dos 2.000 diagn\u00f3sticos positivos pela terceira semana seguida, segundo a Abrafarma (Associa\u00e7\u00e3o Brasileira das Redes de Farm\u00e1cias e Drogarias), associa\u00e7\u00e3o que re\u00fane as grandes empresas do varejo farmac\u00eautico.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Entre os dias 19 e 25 de setembro, foram registradas cerca de 1.200 confirma\u00e7\u00f5es da doen\u00e7a, uma queda de 27% em rela\u00e7\u00e3o aos sete dias anteriores.<\/p>\n<p>De acordo com a Abrafarma, o n\u00famero representa 7% dos mais de 17 mil atendimentos feitos nas drogarias. O patamar \u00e9 o menor desde a implementa\u00e7\u00e3o dos testes nas farm\u00e1cias, em abril de 2020.<\/p>\n<p>A associa\u00e7\u00e3o projeta um cen\u00e1rio com menos de mil casos confirmados semanalmente ainda em outubro.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/1951809\/farmacias-devem-registrar-menos-de-mil-casos-de-covid-ainda-neste-mes?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; Os testes de Covid nas farm\u00e1cias se mantiveram abaixo<\/p>\n","protected":false},"author":0,"featured_media":92658,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-92657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92657"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92658"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}