{"id":92581,"date":"2022-10-03T21:08:02","date_gmt":"2022-10-04T00:08:02","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/ufmt-lanca-edital-com-15-mil-vagas-remanescentes-em-cursos-superiores-em-sinop-e-outras-cidades\/"},"modified":"2022-10-03T21:08:02","modified_gmt":"2022-10-04T00:08:02","slug":"ufmt-lanca-edital-com-15-mil-vagas-remanescentes-em-cursos-superiores-em-sinop-e-outras-cidades","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/ufmt-lanca-edital-com-15-mil-vagas-remanescentes-em-cursos-superiores-em-sinop-e-outras-cidades\/","title":{"rendered":"UFMT lan\u00e7a edital com 1,5 mil vagas remanescentes em cursos superiores em Sinop e outras cidades"},"content":{"rendered":"<p>A Universidade Federal de Mato Grosso (UFMT) lan\u00e7ou edital de processo seletivo espec\u00edfico para ocupa\u00e7\u00e3o de vagas remanescentes do Sistema de Sele\u00e7\u00e3o Unificada (Sisu), para ingresso no segundo semestre letivo de 2022. As inscri\u00e7\u00f5es devem ser feitas pelo portal de ingresso, entre os dias 17 e 21 de outubro. A sele\u00e7\u00e3o ser\u00e1 feita considerando uma das \u00faltimas cinco edi\u00e7\u00f5es do Exame Nacional do Ensino M\u00e9dio (Enem).<\/p>\n<p>As vagas s\u00e3o distribu\u00eddas entre ampla concorr\u00eancia e a\u00e7\u00f5es afirmativas, sendo que as vagas remanescentes de a\u00e7\u00f5es afirmativas do processo seletivo SiSU foram remanejadas para o tipo L5, candidatos que tenham cursado integralmente o ensino m\u00e9dio em escola p\u00fablica independentemente de renda.<\/p>\n<p>Entre ampla concorr\u00eancia e a\u00e7\u00f5es afirmativas, s\u00e3o disponibilizadas 341 vagas para o c\u00e2mpus do Araguaia, 578 para Cuiab\u00e1, 454 para Sinop e 122 para V\u00e1rzea Grande. No ato da inscri\u00e7\u00e3o, a pessoa interessada informa a vaga pretendida por curso de gradua\u00e7\u00e3o e c\u00e2mpus de oferta a partir da rela\u00e7\u00e3o que est\u00e1 presente no edital, que prev\u00ea a possibilidade de altera\u00e7\u00f5es durante o per\u00edodo de inscri\u00e7\u00f5es.<\/p>\n<p>O processo seletivo acontece exclusivamente com base nos resultados do Enem, em que os candidatos ser\u00e3o classificados por ordem da pontua\u00e7\u00e3o global. Para candidatos que tenham realizado mais de uma edi\u00e7\u00e3o do Enem, a sele\u00e7\u00e3o j\u00e1 considera automaticamente a maior pontua\u00e7\u00e3o. O crit\u00e9rio de desempate ser\u00e1 a nota da reda\u00e7\u00e3o.<\/p>\n<p>O deferimento das inscri\u00e7\u00f5es ser\u00e1 divulgado no dia 27 e a convoca\u00e7\u00e3o para envio de documentos da pr\u00e9-matr\u00edcula da primeira chamada no dia 4 de novembro. S\u00e3o previstas 3 chamadas no seletivo, sendo a \u00faltima no dia 14 de dezembro.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Universidade Federal de Mato Grosso (UFMT) lan\u00e7ou edital de processo seletivo espec\u00edfico para ocupa\u00e7\u00e3o<\/p>\n","protected":false},"author":0,"featured_media":92582,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-92581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92581"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92582"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}