{"id":92559,"date":"2022-10-03T18:08:24","date_gmt":"2022-10-03T21:08:24","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/juarez-costa-e-reeleito-deputado-federal-com-votacao-55-maior-em-relacao-ao-1o-mandato\/"},"modified":"2022-10-03T18:08:24","modified_gmt":"2022-10-03T21:08:24","slug":"juarez-costa-e-reeleito-deputado-federal-com-votacao-55-maior-em-relacao-ao-1o-mandato","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/juarez-costa-e-reeleito-deputado-federal-com-votacao-55-maior-em-relacao-ao-1o-mandato\/","title":{"rendered":"Juarez Costa \u00e9 reeleito deputado federal com vota\u00e7\u00e3o 55% maior em rela\u00e7\u00e3o ao 1\u00ba mandato"},"content":{"rendered":"<p>O deputado federal reeleito Juarez Costa (MDB) ampliou sua vota\u00e7\u00e3o, em Mato Grosso. No primeiro mandato (em 2018) ele recebeu 49.912 votos. Ontem, garantiu o segundo mandato com 77.528 votos, sendo 55% maior que h\u00e1 quatro anos.<\/p>\n<p>Juarez comemorou a vit\u00f3ria, em Sinop, com aliados. \u201cEstou feliz pelo trabalho que realizei, estou feliz com a conquista desse segundo mandato e por ter sido o primeiro dentro do partido. Isso \u00e9 muito importante, n\u00e3o foi uma luta f\u00e1cil\u201d. \u201c\u00c9 uma vit\u00f3ria de trabalho, de dedica\u00e7\u00e3o, de muita entrega. E a gente quer continuar mostrando que a gente tem a elei\u00e7\u00e3o pelo trabalho\u201d e\u201d vamos continuar trabalhando, nos dedicando para ajudar Sinop, e para ajudar o Estado\u201d, declarou, atrav\u00e9s da assessoria. \u201cFoi uma elei\u00e7\u00e3o muito importante, primeiro que eu confiei nos pequenos munic\u00edpios, tive um olhar diferenciado para os pequenos. Trabalhei muito, foram quase quatro anos de muita entrega, de muitos recursos, principalmente para aqueles munic\u00edpios que n\u00e3o tinham um olhar de um deputado federal\u201d, analisou.<\/p>\n<p>Em Sinop \u2013 maior col\u00e9gio eleitoral do Nort\u00e3o e onde reside -, Juarez obteve ontem 16.478 votos (22,17%). Na elei\u00e7\u00e3o de 2018, quando conquistou primeiro mandato, fez vota\u00e7\u00e3o maior, 21.438 votos. Na elei\u00e7\u00e3o, h\u00e1 dois anos, para prefeito, quando Roberto Dorner foi eleito, Juarez obteve 18.097 votos.<\/p>\n<p>Na vota\u00e7\u00e3o geral, Juarez Costa foi o 4\u00ba mais votado, ficando \u00e0 frente do reeleito Emanuelzinho Pereira e dos eleitos, Am\u00e1lia Barros, coronel Fernanda e coronel Assis.<\/p>\n<p>Resultado em Mato Grosso<br \/>\nProfessora Rosa Neide 124.671 votos ( n\u00e3o \u00e9 considerada eleita devido ao quociente eleitoral)<br \/>\nF\u00e1bio Garcia 98.698 eleito<br \/>\nAb\u00edlio Brunini 87.072 eleito<br \/>\nJos\u00e9 Medeiros 82.180\u00a0eleito<br \/>\nJuarez Costa 77.528\u00a0reeleito<br \/>\nEmanuelzinho 74.648\u00a0reeleito<br \/>\nAm\u00e1lia Barros 70.289\u00a0eleita<br \/>\nCoronel Fernanda 60.298\u00a0eleita<br \/>\nCoronel Assis 47.475\u00a0eleito<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal reeleito Juarez Costa (MDB) ampliou sua vota\u00e7\u00e3o, em Mato Grosso. No primeiro<\/p>\n","protected":false},"author":0,"featured_media":92560,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92559"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92560"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}