{"id":92496,"date":"2022-10-03T12:08:05","date_gmt":"2022-10-03T15:08:05","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/deputado-federal-eleito-coronel-assis-diz-que-trabalhara-dia-e-noite-pela-reeleicao-de-bolsonaro\/"},"modified":"2022-10-03T12:08:05","modified_gmt":"2022-10-03T15:08:05","slug":"deputado-federal-eleito-coronel-assis-diz-que-trabalhara-dia-e-noite-pela-reeleicao-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/deputado-federal-eleito-coronel-assis-diz-que-trabalhara-dia-e-noite-pela-reeleicao-de-bolsonaro\/","title":{"rendered":"Deputado federal eleito, coronel Assis diz que trabalhar\u00e1 \u2018dia e noite\u2019 pela reelei\u00e7\u00e3o de Bolsonaro"},"content":{"rendered":"<p>O deputado federal eleito pelo Uni\u00e3o Brasil com 47.479 mil votos, coronel Assis, ex-comandante geral da Pol\u00edcia Militar,agradeceu aos mato-grossenses pela vit\u00f3ria nas urnas, ontem, e avaliou que \u201c\u00e9 poss\u00edvel ver um saldo muito positivo neste primeiro turno, visto que a bancada federal por Mato Grosso est\u00e1 fortemente alinhada com o presidente Bolsonaro e representa muito bem o resultado de praticamente 60% dos votos recebidos por ele aqui no Estado\u201d.\u00a0 Ele acrescentou que, agora, vai trabalhar \u201cdia e noite\u201d pela reelei\u00e7\u00e3o de Jair Bolsonaro e analisa que o presidente j\u00e1 sai vencedor neste primeiro turno tendo angariado no Congresso Nacional maioria de parlamentares de direita.<\/p>\n<p>\u201cSempre acreditei que se voc\u00ea quer voar como \u00e1guia, tem que voar com as \u00e1guias. No Uni\u00e3o Brasil participei de uma chapa muito forte e consolidada, e que agora sai fortalecida com duas vagas na bancada federal. N\u00e3o tenho d\u00favidas que essa for\u00e7a vai ser convertida em muito trabalho para Mato Grosso e para o pa\u00eds\u201d, apontou.<\/p>\n<p>Assis acrescentou que\u00a0 \u201ca seguran\u00e7a \u00e9 a nossa principal bandeira, mas entendemos que Mato Grosso tamb\u00e9m precisa se industrializar e se desenvolver e al\u00e9m disso, avan\u00e7armos com as Escolas Militares no Estado. Na C\u00e2mara Federal vamos combater a impunidade com a revis\u00e3o das leis penais, e tamb\u00e9m vamos lutar pelo desenvolvimento do nosso Estado\u201d, declarou.<\/p>\n<p>Depois de ter comemorado a vit\u00f3ria com seus apoiadores em uma carreata que encerrou com o recebimento dos cumprimentos dos familiares e amigos no bairro Jardim Gl\u00f3ria, em V\u00e1rzea Grande, Assis j\u00e1 come\u00e7ou a semana fortalecendo seu plano de a\u00e7\u00e3o parlamentar.<\/p>\n<p>\u00a0<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal eleito pelo Uni\u00e3o Brasil com 47.479 mil votos, coronel Assis, ex-comandante geral<\/p>\n","protected":false},"author":0,"featured_media":92497,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92496"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92497"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}