{"id":92441,"date":"2022-10-03T06:08:45","date_gmt":"2022-10-03T09:08:45","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/horario-de-verao-em-2022-veja-o-que-diz-o-estudo-tecnico-que-embasara-a-decisao\/"},"modified":"2022-10-03T06:08:45","modified_gmt":"2022-10-03T09:08:45","slug":"horario-de-verao-em-2022-veja-o-que-diz-o-estudo-tecnico-que-embasara-a-decisao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/horario-de-verao-em-2022-veja-o-que-diz-o-estudo-tecnico-que-embasara-a-decisao\/","title":{"rendered":"Hor\u00e1rio de ver\u00e3o em 2022? veja o que diz o estudo t\u00e9cnico que embasar\u00e1 a decis\u00e3o"},"content":{"rendered":"<p>Novos estudos do Operador Nacional do Sistema El\u00e9trico (ONS) apontam que a aplica\u00e7\u00e3o do hor\u00e1rio de ver\u00e3o neste ano n\u00e3o traz benef\u00edcios para a opera\u00e7\u00e3o do sistema el\u00e9trico nacional. A an\u00e1lise sobre a possibilidade de retomar o mecanismo, extinto em 2019 pelo presidente Jair Bolsonaro, foi feita a pedido do Minist\u00e9rio de Minas e Energia (MME) em agosto. Apesar do parecer, a decis\u00e3o sobre a medida caber\u00e1 ao governo federal.<\/p>\n<p>Os resultados devem ser apresentados na pr\u00f3xima reuni\u00e3o do Comit\u00ea de Monitoramento do Setor El\u00e9trico (CMSE), colegiado presidido pelo ministro de Minas e Energia, Adolfo Sachsida. O encontro est\u00e1 previsto para a pr\u00f3xima quarta-feira, 5.<\/p>\n<\/p>\n<p>&#8220;O Operador Nacional do Sistema El\u00e9trico (ONS) informa que conduziu an\u00e1lises sobre uma poss\u00edvel aplica\u00e7\u00e3o do Hor\u00e1rio de Ver\u00e3o em 2022. Os resultados obtidos n\u00e3o apontaram benef\u00edcios para a opera\u00e7\u00e3o do SIN [Sistema Interligado Nacional] decorrentes dessa medida. Neste contexto, o ONS refor\u00e7a que cabe ao Governo Federal definir se aplicar\u00e1 ou n\u00e3o a medida&#8221;, informou o ONS ao <b>Estad\u00e3o\/Broadcast<\/b>.<\/p>\n<\/p>\n<p>Criado com a finalidade de aproveitar o maior per\u00edodo de luz solar durante a \u00e9poca mais quente do ano, o hor\u00e1rio de ver\u00e3o foi institu\u00eddo no Brasil em 1931 pelo ent\u00e3o presidente Get\u00falio Vargas e adotado em car\u00e1ter permanente a partir de 2008. Mas, mudan\u00e7as nos h\u00e1bitos do consumidor e avan\u00e7o da tecnologia reduziram a relev\u00e2ncia da economia de energia ao longo dos anos. Esse foi o argumento usado pelo governo para extinguir a medida em 2019.<\/p>\n<\/p>\n<p>O novo estudo foi solicitado justamente para entender se houve alguma altera\u00e7\u00e3o nesse cen\u00e1rio com o crescimento da gera\u00e7\u00e3o de energia solar, sobretudo pela expans\u00e3o dos sistemas de gera\u00e7\u00e3o distribu\u00edda. O objetivo era entender quais seriam os efeitos de adiantar o pico de consumo do in\u00edcio da noite para um hor\u00e1rio em que ainda h\u00e1 sol e gera\u00e7\u00e3o dessa fonte, o que poderia reduzir a necessidade de acionar outras que podem custar mais caro.<\/p>\n<\/p>\n<p>No passado, em meio \u00e0 crise h\u00eddrica e press\u00e3o crescente de alguns setores da economia, o MME tamb\u00e9m solicitou uma avalia\u00e7\u00e3o sobre a volta do mecanismo. O estudo entregue \u00e0 pasta apresentou o mesmo argumento usado em 2019: a medida n\u00e3o traria economia de energia. A avalia\u00e7\u00e3o apontou que o hor\u00e1rio de ver\u00e3o poderia ajudar, mesmo que pouco, a atenuar o consumo nos hor\u00e1rios de ponta. Diante do diagn\u00f3stico, o governo descartou a volta do hor\u00e1rio de ver\u00e3o. As informa\u00e7\u00f5es s\u00e3o do jornal <b>O Estado de S. Paulo.<\/b><\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1951406\/horario-de-verao-em-2022-veja-o-que-diz-o-estudo-tecnico-que-embasara-a-decisao?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novos estudos do Operador Nacional do Sistema El\u00e9trico (ONS) apontam que a aplica\u00e7\u00e3o do hor\u00e1rio<\/p>\n","protected":false},"author":0,"featured_media":92442,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-92441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92441"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92442"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}