{"id":92433,"date":"2022-10-03T06:08:33","date_gmt":"2022-10-03T09:08:33","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/rei-charles-3o-aparece-em-primeira-foto-oficial-da-realeza\/"},"modified":"2022-10-03T06:08:33","modified_gmt":"2022-10-03T09:08:33","slug":"rei-charles-3o-aparece-em-primeira-foto-oficial-da-realeza","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/03\/rei-charles-3o-aparece-em-primeira-foto-oficial-da-realeza\/","title":{"rendered":"Rei Charles 3\u00ba aparece em primeira foto oficial da realeza"},"content":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; A fam\u00edlia real brit\u00e2nica divulgou neste final de semana a primeira foto oficial de Charles 3\u00ba como rei e de sua mulher, Camilla, como rainha consorte. No retrato, publicado no perfil oficial do Instagram da realeza, o casal aparece ao lado do herdeiro do trono, William, que assumiu o t\u00edtulo de pr\u00edncipe de Gales, e de sua mulher, Kate Middleton, agora princesa de Gales.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>A foto em que todos aparecem sorridentes (Charles, de forma mais t\u00edmida), foi feita no \u00faltimo dia 18 de setembro, no Pal\u00e1cio de Buckingham, na noite anterior ao funeral da rainha Elizabeth 2\u00aa. Ela havia morrido dez dias antes, em 8 de setembro.<\/p>\n<p>&#8220;Suas Majestades o Rei e a Rainha Consorte com Suas Altezas Reais o Pr\u00edncipe e a Princesa de Gales&#8221;, diz a legenda da publica\u00e7\u00e3o, que informa tamb\u00e9m o nome do fot\u00f3grafo, Chris Jackson. A cerim\u00f4nia oficial de coroa\u00e7\u00e3o do Rei Charles 3\u00ba deve ocorrer em 2023, em data que ainda n\u00e3o foi divulgada.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Fama<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/fama\/1951409\/rei-charles-3-aparece-em-primeira-foto-oficial-da-realeza?utm_source=rss-fama&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIO DE JANEIRO, RJ (FOLHAPRESS) &#8211; A fam\u00edlia real brit\u00e2nica divulgou neste final de semana<\/p>\n","protected":false},"author":0,"featured_media":92434,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-92433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama-e-tv"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92433"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92434"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}