{"id":92415,"date":"2022-10-02T18:08:44","date_gmt":"2022-10-02T21:08:44","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/02\/nova-liga-dos-campeoes-so-acelera-a-decadencia-do-futebol-diz-presidente-do-real\/"},"modified":"2022-10-02T18:08:44","modified_gmt":"2022-10-02T21:08:44","slug":"nova-liga-dos-campeoes-so-acelera-a-decadencia-do-futebol-diz-presidente-do-real","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/02\/nova-liga-dos-campeoes-so-acelera-a-decadencia-do-futebol-diz-presidente-do-real\/","title":{"rendered":"Nova Liga dos Campe\u00f5es s\u00f3 acelera a decad\u00eancia do futebol, diz presidente do Real"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Florentino P\u00e9rez, presidente do Real Madrid, criticou o novo formato da Liga dos Campe\u00f5es, que come\u00e7ar\u00e1 a valer na temporada 2024\/2025. Para ele, essa mudan\u00e7a s\u00f3 prejudica o futebol europeu.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>&#8220;Por raz\u00f5es que n\u00e3o podemos entender, a UEFA est\u00e1 indo na dire\u00e7\u00e3o oposta. O novo modelo servir\u00e1 apenas para distanciar mais f\u00e3s e acelerar o decl\u00ednio do futebol&#8221;, lamentou o dirigente.<\/p>\n<p>Antes, o presidente deu sua opini\u00e3o sobre o momento atual que a modalidade esportiva vive no continente europeu. &#8220;Para resolver um problema, voc\u00ea deve primeiro reconhecer que tem um problema. Nosso amado esporte est\u00e1 doente na Europa, est\u00e1 perdendo sua lideran\u00e7a. Os jovens est\u00e3o cada vez menos interessados, exigem um produto de qualidade que as competi\u00e7\u00f5es europeias atuais n\u00e3o oferecem&#8221;.<\/p>\n<p>Como parte da argumenta\u00e7\u00e3o, Florentino usou como exemplo as dezenas de embates entre Rafael Nadal e Roger Federer, dois dos maiores tenistas de todos os tempos.<\/p>\n<p>&#8220;Nadal e Federer jogaram 40 vezes ao longo dos anos, Nadal e Djokovic&#8230; Liverpool, n\u00f3s jogamos contra eles nove vezes em 67 anos. Chelsea quatro vezes na hist\u00f3ria da Copa da Europa e as duas \u00faltimas nestes anos. Qual \u00e9 o sentido de privar os torcedores desses jogos?&#8221;, indagou o presidente.<\/p>\n<p>Vale lembrar que o Real Madrid \u00e9 o maior vencedor da hist\u00f3ria da Liga dos Campe\u00f5es, com 14 conquistas, sendo que a \u00faltimas delas aconteceu justamente na \u00faltima temporada.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1951085\/nova-liga-dos-campeoes-so-acelera-a-decadencia-do-futebol-diz-presidente-do-real?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (UOL\/FOLHAPRESS) &#8211; Florentino P\u00e9rez, presidente do Real Madrid, criticou o novo formato<\/p>\n","protected":false},"author":0,"featured_media":92416,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-92415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92415"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92416"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}