{"id":92397,"date":"2022-10-02T17:08:31","date_gmt":"2022-10-02T20:08:31","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/02\/mesaria-se-recusa-a-cumprimentar-fernando-haddad-durante-votacao\/"},"modified":"2022-10-02T17:08:31","modified_gmt":"2022-10-02T20:08:31","slug":"mesaria-se-recusa-a-cumprimentar-fernando-haddad-durante-votacao","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/02\/mesaria-se-recusa-a-cumprimentar-fernando-haddad-durante-votacao\/","title":{"rendered":"Mes\u00e1ria se recusa a cumprimentar Fernando Haddad durante vota\u00e7\u00e3o"},"content":{"rendered":"<p>ISABELLA MENON (FOLHAPRESS) &#8211; Em imagens que viralizaram nas redes sociais, Fernando Haddad, candidato do PT para governo de S\u00e3o Paulo, cumprimenta os mes\u00e1rios da sua se\u00e7\u00e3o.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Por\u00e9m, uma delas se recusa a cumpriment\u00e1-lo. Haddad insiste no cumprimento, mas quando nota a recusa, desiste.<\/p>\n<p>Ele votou na manh\u00e3 deste domingo (2) no Col\u00e9gio Catamar\u00e3, em Moema, bairro da zona sul de S\u00e3o Paulo.<\/p>\n<p>A assessoria de imprensa do candidato confirmou \u00e0 Folha que o fato aconteceu neste domingo (2), mas disse que n\u00e3o vai comentar o ocorrido.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/1951067\/mesaria-se-recusa-a-cumprimentar-fernando-haddad-durante-votacao?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ISABELLA MENON (FOLHAPRESS) &#8211; Em imagens que viralizaram nas redes sociais, Fernando Haddad, candidato do<\/p>\n","protected":false},"author":0,"featured_media":92398,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-92397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92397"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92398"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}