{"id":92391,"date":"2022-10-02T16:08:38","date_gmt":"2022-10-02T19:08:38","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/10\/02\/filas-sao-influenciadas-por-alto-comparecimento-diz-tre-mg\/"},"modified":"2022-10-02T16:08:38","modified_gmt":"2022-10-02T19:08:38","slug":"filas-sao-influenciadas-por-alto-comparecimento-diz-tre-mg","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/10\/02\/filas-sao-influenciadas-por-alto-comparecimento-diz-tre-mg\/","title":{"rendered":"Filas s\u00e3o influenciadas por alto comparecimento, diz TRE-MG"},"content":{"rendered":"<p>(FOLHAPRESS) &#8211; O TRE-MG divulgou nota na tarde deste domingo (2) afirmando que as longas filas registradas nas se\u00e7\u00f5es eleitorais do estado s\u00e3o influenciadas pelo comparecimento em grande volume de eleitores.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>O tribunal afirma ainda que outro fator que contribui para a espera para o acesso \u00e0s urnas \u00e9 o tempo que os eleitores demoram para votar, por estarem em disputa cinco cargos.<\/p>\n<p>&#8220;O TRE-MG informa que foi detectada a forma\u00e7\u00e3o de filas em muitos locais de vota\u00e7\u00e3o, em raz\u00e3o do comparecimento de um grande volume de eleitores para votar a partir do meio da manh\u00e3&#8221;, diz a nota.<\/p>\n<p>&#8220;A forma\u00e7\u00e3o de filas tamb\u00e9m \u00e9 influenciada pelo tempo que cada pessoa demora para votar, j\u00e1 que s\u00e3o cinco cargos em disputa. Esse \u00e9 um fato registrado em toda elei\u00e7\u00e3o geral.<\/p>\n<p>Segundo o TRE, todas as pessoas que estiverem na fila das suas se\u00e7\u00f5es eleitorais at\u00e9 as 17h receber\u00e3o uma senha para que possam votar normalmente.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/politica\/1951046\/filas-sao-influenciadas-por-alto-comparecimento-diz-tre-mg?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(FOLHAPRESS) &#8211; O TRE-MG divulgou nota na tarde deste domingo (2) afirmando que as longas<\/p>\n","protected":false},"author":0,"featured_media":92392,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-92391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92391"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92392"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}