{"id":92181,"date":"2022-09-30T16:08:04","date_gmt":"2022-09-30T19:08:04","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/30\/transferencia-de-controle-da-br-163-de-sinop-ao-ms-para-o-governo-do-estado-depende-de-negociacao-de-dividas\/"},"modified":"2022-09-30T16:08:04","modified_gmt":"2022-09-30T19:08:04","slug":"transferencia-de-controle-da-br-163-de-sinop-ao-ms-para-o-governo-do-estado-depende-de-negociacao-de-dividas","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/30\/transferencia-de-controle-da-br-163-de-sinop-ao-ms-para-o-governo-do-estado-depende-de-negociacao-de-dividas\/","title":{"rendered":"Transfer\u00eancia de controle da BR-163 de Sinop ao MS para o governo do Estado depende de negocia\u00e7\u00e3o de d\u00edvidas"},"content":{"rendered":"<p>O processo de transfer\u00eancia do controle acion\u00e1rio da BR-163, de Sinop ao Mato Grosso do Sul, da concession\u00e1ria Rota do Oeste para o governo de Mato Grosso, ap\u00f3s aprova\u00e7\u00e3o pelo Tribunal de Contas da Uni\u00e3o, entra na segunda etapa, com a renegocia\u00e7\u00e3o de d\u00edvidas junto aos bancos que financiaram a primeira parte da duplica\u00e7\u00e3o da rodovia com a empresa. N\u00e3o foi informado o montante.<\/p>\n<p>O secret\u00e1rio-chefe da Casa Civil, Rog\u00e9rio Gallo e ex-secret\u00e1rio de Finan\u00e7as, explica que \u201co nosso modelo negocial prev\u00ea uma redu\u00e7\u00e3o das d\u00edvidas de financiamento, e, para que isso aconte\u00e7a, os bancos t\u00eam que aceitar. Metade das d\u00edvidas s\u00e3o com a Caixa Econ\u00f4mica Federal e o Banco do Brasil, ent\u00e3o podemos dizer que est\u00e1 nas m\u00e3os dos bancos p\u00fablicos a solu\u00e7\u00e3o do pr\u00f3ximo passo que ser\u00e1 dado com o TAC para a BR-163\u201d, explicou. Ao comprar as cotas de participa\u00e7\u00e3o da Odebrecht Transport por R$ 1, por meio da MT Participa\u00e7\u00f5es e Projetos (MT Par), o governo de Mato Grosso assume as d\u00edvidas contra\u00eddas pela Rota do Oeste para a duplica\u00e7\u00e3o de 120 km da BR-163, entre Itiquira e Rondon\u00f3polis, na regi\u00e3o Sul. Entretanto, diante dos investimentos que ainda ser\u00e3o realizados para que a duplica\u00e7\u00e3o da estrada seja conclu\u00edda, o Governo busca a renegocia\u00e7\u00e3o dessas d\u00edvidas.<\/p>\n<p>\u201c\u00c9 importante que esses bancos p\u00fablicos tenham a sensibilidade de observar que, no lugar do ente privado, est\u00e1 entrando uma empresa com capital p\u00fablico que n\u00e3o objetiva estritamente o lucro, mas que busca resolver um problema sobre o qual movimenta-se 50% da popula\u00e7\u00e3o de Mato Grosso e uma parte relevante do PIB agropecu\u00e1rio brasileiro\u201d, destacou.<\/p>\n<p>O termo de ajustamento de conduta entre a ANTT\u00a0 (Ag\u00eancia Nacional de Transporte Terrestre) e a Rota deve ser assinado na pr\u00f3xima ter\u00e7a-feira (4), contando com uma cl\u00e1usula suspensiva, at\u00e9 que a an\u00e1lise dos bancos seja conclu\u00edda. A proposta do governo do Estado \u00e9 de nos pr\u00f3ximos dois anos investir R$ 1,2 bilh\u00e3o para a conclus\u00e3o das obras no trecho mato-grossense da BR-163, com recursos pr\u00f3prios. Desse valor, R$ 300 milh\u00f5es j\u00e1 est\u00e3o no caixa da empresa estadual, enquanto o restante dos valores ser\u00e1 repassado pelo Estado, segundo previs\u00e3o or\u00e7ament\u00e1ria.<\/p>\n<p>O secret\u00e1rio lembrou que Mato Grosso foi reconhecido, neste m\u00eas, como 1\u00ba do pa\u00eds no quesito Solidez Fiscal, de acordo com o Ranking de Competitividade dos Estados, o que comprova a sa\u00fade financeira do Estado. Ele ainda acrescentou que o investimento do Governo para a aquisi\u00e7\u00e3o do controle acion\u00e1rio da BR-163 tem um forte componente social, diante da import\u00e2ncia da rodovia para o Estado.<\/p>\n<p>\u201c\u00c9 uma vergonha para o Brasil e Mato Grosso continuarmos com uma rodovia importante como esta nessas condi\u00e7\u00f5es. Esse investimento \u00e9 o respeito que temos com a nossa popula\u00e7\u00e3o e com os usu\u00e1rios que v\u00eam do Brasil inteiro. Quantas vidas n\u00e3o vamos poupar? Esse investimento sinaliza menor perda de vidas e de produtividade ao longo desse trecho. \u00c9 para isso que o Estado existe, para oferecer solu\u00e7\u00f5es, e eu n\u00e3o tenho d\u00favidas que seremos um case importante na hist\u00f3ria da infraestrutura do Brasil\u201d, ressaltou.<\/p>\n<p>Conforme S\u00f3 Not\u00edcias j\u00e1 informou, na \u00faltima quarta-feira (28), o Tribunal de Contas da Uni\u00e3o reconheceu como inovadora a solu\u00e7\u00e3o apresentada pelo Governo de Mato Grosso e a Ag\u00eancia Nacional de Transportes Terrestres (ANTT) para o imbr\u00f3glio envolvendo a concess\u00e3o da BR-163. A Rota do Oeste se comprometeu, ao assumir a via em 2014, a duplicar mais de 450 km de asfalto no Estado. Mas s\u00f3 fez 120 km. O n\u00e3o cumprimento do contrato passou a ser apontado como a principal causa de mortes registradas na rodovia.<\/p>\n<p>Ano passado, a Rota do Oeste, ap\u00f3s diversas a\u00e7\u00f5es e mobiliza\u00e7\u00e3o de entidades mato-grossenses com coordena\u00e7\u00e3o da OAB e lideran\u00e7as pol\u00edticas para a empresa deixar de ser concession\u00e1ria por n\u00e3o cumprir o contrato, acabou concordando com a devolu\u00e7\u00e3o amig\u00e1vel da concess\u00e3o, ap\u00f3s a intensifica\u00e7\u00e3o das cobran\u00e7as quanto a uma solu\u00e7\u00e3o. Contudo, conforme a ANTT, o processo de uma nova licita\u00e7\u00e3o poderia levar at\u00e9 tr\u00eas anos, e resultaria em um aumento no pre\u00e7o da tarifa de ped\u00e1gio.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O processo de transfer\u00eancia do controle acion\u00e1rio da BR-163, de Sinop ao Mato Grosso do<\/p>\n","protected":false},"author":0,"featured_media":92182,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-92181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92181"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92182"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}