{"id":92069,"date":"2022-09-29T16:21:40","date_gmt":"2022-09-29T19:21:40","guid":{"rendered":"http:\/\/roteironoticias.com.br\/?p=92069"},"modified":"2022-09-29T17:00:50","modified_gmt":"2022-09-29T20:00:50","slug":"sindicato-rural-de-guaranta-do-norte-e-senar-disponibilizam-dois-cursos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/29\/sindicato-rural-de-guaranta-do-norte-e-senar-disponibilizam-dois-cursos\/","title":{"rendered":"Sindicato Rural de Guarant\u00e3 do Norte e Senar disponibilizam dois cursos"},"content":{"rendered":"\n<p>O sindicato Rural de Guarant\u00e3 dom Norte\/MT, e o Senar estar\u00e3o realizando mais dois cursos voltados para qualifica\u00e7\u00e3o de m\u00e3o de obra, dando assim oportunidade para as pessoas ingressarem no mercado de trabalho.<\/p>\n\n\n\n<p>Os interessados em buscarem uma profiss\u00e3o ou mesmo estarem se aperfei\u00e7oando podem estarem realizando suas matriculas, para assim assegurarem suas vagas, uma vez que, s\u00e3o apenas 15 vagas por curso.<\/p>\n\n\n\n<p>Entre os dias 03 a 07 de outubro, estar\u00e1 sendo realizado o curso de classifica\u00e7\u00e3o de gr\u00e3os de soja e milho, com uma carga hor\u00e1ria de 40 horas de cursos e ap\u00f3s o termino, os cursistas estar\u00e3o recebendo o certificado de conclus\u00e3o.<\/p>\n\n\n\n<p>J\u00e1 nos dias 24 a 26 de outubro, acontece o curso de NR 35 (trabalho nas alturas), o curso ser\u00e1 em tempo integral com uma carga hor\u00e1ria de 24 horas, com certificado de conclus\u00e3o ap\u00f3s o curso.<\/p>\n\n\n\n<p>Para maiores informa\u00e7\u00f5es os interessados podem estarem entrando em contato pelos celulares, (<strong>66) 98436 5123 (France), (66) 98436 5354 (Ademir), (66) 99978 2469 (Cida)<\/strong>. Os interessados em estarem fazendo o curto t\u00eam de ser acima de 18 anos.<\/p>\n\n\n\n<p><strong><em><span class=\"has-inline-color has-vivid-red-color\">Por C\u00e9lio Ribeiro\/Roteiro Not\u00edcias<\/span><\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"180\" src=\"http:\/\/roteironoticias.com.br\/wp-content\/uploads\/2022\/09\/nr-35.jpg\" alt=\"\" class=\"wp-image-92071\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O sindicato Rural de Guarant\u00e3 dom Norte\/MT, e o Senar estar\u00e3o realizando mais dois cursos<\/p>\n","protected":false},"author":2,"featured_media":92070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,2,37],"tags":[],"class_list":["post-92069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-agronoticias","category-regionais"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92069"}],"version-history":[{"count":3,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92069\/revisions"}],"predecessor-version":[{"id":92081,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92069\/revisions\/92081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92070"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}