{"id":92013,"date":"2022-09-29T10:08:12","date_gmt":"2022-09-29T13:08:12","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/29\/governo-protocola-projeto-de-venda-do-porto-de-santos-no-tcu\/"},"modified":"2022-09-29T10:08:12","modified_gmt":"2022-09-29T13:08:12","slug":"governo-protocola-projeto-de-venda-do-porto-de-santos-no-tcu","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/29\/governo-protocola-projeto-de-venda-do-porto-de-santos-no-tcu\/","title":{"rendered":"Governo protocola projeto de venda do Porto de Santos no TCU"},"content":{"rendered":"<p>Ap\u00f3s quase tr\u00eas meses de atraso ante o cronograma original, o governo protocolou oficialmente, no dia 23, no Tribunal de Contas da Uni\u00e3o (TCU) o projeto de privatiza\u00e7\u00e3o do Porto de Santos. Os sucessivos adiamentos para a entrega final da proposta fazem com que o tema chegue \u00e0 Corte com poucas perspectivas. Apesar de o governo insistir em prever o leil\u00e3o neste ano, fontes que acompanham o processo j\u00e1 reconhecem esse cen\u00e1rio como, no m\u00ednimo, improv\u00e1vel. Al\u00e9m dos atrasos e da complexidade inerente ao caso, o projeto foi apresentado ao tribunal com outro complicador: a indefini\u00e7\u00e3o sobre o que ser\u00e1 feito com a \u00e1rea em que o Minist\u00e9rio da Infraestrutura planeja transformar em um superterminal para movimenta\u00e7\u00e3o de cont\u00eaineres em Santos.<\/p>\n<p>Caso o certame n\u00e3o ocorra neste ano, as chances de a privatiza\u00e7\u00e3o do maior complexo portu\u00e1rio da Am\u00e9rica Latina sair do papel s\u00e3o reduzidas. Primeiro colocado nas pesquisas de inten\u00e7\u00e3o de voto \u00e0 Presid\u00eancia, o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) avalia paralisar o projeto, se eleito. Pelo menos \u00e9 o que indica a equipe do petista respons\u00e1vel pelas propostas para a \u00e1rea de infraestrutura. A ex-ministra do Planejamento Miriam Belchior (no governo de Dilma Roussef) afirmou ao Estad\u00e3o\/Broadcast que o time de Lula tem &#8220;enorme preocupa\u00e7\u00e3o&#8221; com o modelo formatado pelo governo Bolsonaro e que avalia como alternativa fazer a concess\u00e3o de servi\u00e7os espec\u00edficos das companhias docas, como o de dragagem.<\/p>\n<\/p>\n<p>Como mostrou no in\u00edcio do m\u00eas o <b>Estad\u00e3o\/Broadcast<\/b>, sistema de not\u00edcias em tempo real do Grupo Estado, antes de o projeto de privatiza\u00e7\u00e3o chegar oficialmente ao TCU, auditores do tribunal estavam cientes de que o presidente da Corte e relator da privatiza\u00e7\u00e3o, ministro Bruno Dantas, queria examinar o caso no menor prazo poss\u00edvel. \u00c0 \u00e9poca, o governo indicava que enviaria a modelagem at\u00e9 16 de setembro &#8211; previs\u00e3o que n\u00e3o se cumpriu. Antes de bater o martelo, o Executivo precisa da aprova\u00e7\u00e3o do TCU, o que \u00e9 seguido pela publica\u00e7\u00e3o do edital. S\u00f3 depois, o leil\u00e3o pode ser realizado. <\/p>\n<\/p>\n<p><b>Disputas e curto prazo p\u00f5em leil\u00e3o em xeque<\/b><\/p>\n<\/p>\n<p>Al\u00e9m do cronograma apertado para a realiza\u00e7\u00e3o do leil\u00e3o do Porto de Santos, a falta de entendimento sobre o arrendamento do terminal para movimenta\u00e7\u00e3o de cont\u00eaineres (STS10) piora a situa\u00e7\u00e3o, apontam fontes. No plano do governo, o porto seria concedido \u00e0 iniciativa privada com a \u00e1rea do STS10 j\u00e1 resolvida. A possibilidade ou n\u00e3o de armadores (empresas de navega\u00e7\u00e3o) disputarem a administra\u00e7\u00e3o do terminal atrasou o cronograma.<\/p>\n<\/p>\n<p>O Executivo ficou encurralado em meio \u00e0 briga do setor &#8211; que op\u00f4s companhias de navega\u00e7\u00e3o, que querem participar do leil\u00e3o do STS10, e a Associa\u00e7\u00e3o Brasileira de Terminais Portu\u00e1rios (ABTP), contra a entrada dessas empresas no certame. Como resultado, at\u00e9 o momento o projeto do STS10 n\u00e3o foi nem mesmo aprovado pela Ag\u00eancia Nacional de Transportes Terrestres (Antaq).<\/p>\n<\/p>\n<p>Na avalia\u00e7\u00e3o de uma fonte, a quest\u00e3o s\u00f3 ser\u00e1 decidida no momento da publica\u00e7\u00e3o do edital. Em nota, o Minist\u00e9rio da Infraestrutura informa que pretende enviar em outubro as propostas de arrendamento do STS10 e STS53 \u00e0 Corte de Contas. A pasta ainda afirma que mant\u00e9m a previs\u00e3o de realizar o leil\u00e3o no quarto trimestre deste ano.<\/p>\n<p> As informa\u00e7\u00f5es s\u00e3o do jornal <b>O Estado de S. Paulo.<\/b><\/p>\n<p><a href=\"https:\/\/www.noticiasaominuto.com.br\/economia\/1949582\/governo-protocola-projeto-de-venda-do-porto-de-santos-no-tcu?utm_source=rss-economia&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><br \/>\nNot\u00edcias ao Minuto Brasil &#8211; Economia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s quase tr\u00eas meses de atraso ante o cronograma original, o governo protocolou oficialmente, no<\/p>\n","protected":false},"author":0,"featured_media":92014,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-92013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=92013"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/92013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/92014"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=92013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=92013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=92013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}