{"id":91685,"date":"2022-09-27T08:08:08","date_gmt":"2022-09-27T11:08:08","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/27\/tribunal-nega-recurso-do-estado-e-mantem-prescricao-de-acao-que-questionava-obra-em-sinop\/"},"modified":"2022-09-27T08:08:08","modified_gmt":"2022-09-27T11:08:08","slug":"tribunal-nega-recurso-do-estado-e-mantem-prescricao-de-acao-que-questionava-obra-em-sinop","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/27\/tribunal-nega-recurso-do-estado-e-mantem-prescricao-de-acao-que-questionava-obra-em-sinop\/","title":{"rendered":"Tribunal nega recurso do Estado e mant\u00e9m prescri\u00e7\u00e3o de a\u00e7\u00e3o que questionava obra em Sinop"},"content":{"rendered":"<p>O Tribunal de Justi\u00e7a decidiu manter a prescri\u00e7\u00e3o de uma a\u00e7\u00e3o movida pelo Estado de Mato Grosso contra uma empreiteira, por supostas irregularidades na constru\u00e7\u00e3o do Centro de Forma\u00e7\u00e3o Profissional (Cenfor) em Sinop. O Estado pedia o ressarcimento de R$ 31 mil aos cofres p\u00fablicos, mas o caso foi julgado prescrito pela 3\u00aa Vara Especializada da Fazenda P\u00fablica da Comarca de Cuiab\u00e1.<\/p>\n<p>Na a\u00e7\u00e3o, o Estado apontou que, em junho de 2001, a secretaria de Educa\u00e7\u00e3o firmou contrato com a empresa para constru\u00e7\u00e3o do Cenfor. No entanto, al\u00e9m de irregularidades na obra, o Estado alega que a empreiteira entregou a unidade com cinco salas, uma a menos do que o previsto, o que resultou em preju\u00edzo de R$ 31 mil.<\/p>\n<p>A empresa, no entanto, garante que a obra foi entregue de acordo com o projeto e o or\u00e7amento, j\u00e1 que a unidade de Sinop tinha como modelo o Cenfor de Alta Floresta, o qual possui cinco salas e n\u00e3o seis. No entendimento da Justi\u00e7a, a obra foi conclu\u00edda em 2002 e o Estado protocolou a a\u00e7\u00e3o de ressarcimento um ano depois do prazo prescricional.<\/p>\n<p>No recurso, por\u00e9m, o Estado alegou que a demanda n\u00e3o se trata apenas de \u201csimples inadimplemento contratual\u201d e, sim, de atos de \u201cimprobidade administrativa\u201d, na modalidade \u201cles\u00e3o ao er\u00e1rio\u201d, os quais s\u00e3o imprescrit\u00edveis. Ao julgar o recurso, o Tribunal de Justi\u00e7a entendeu, entretanto, que o Estado apresentou \u201ctese in\u00e9dita\u201d de improbidade administrativa, n\u00e3o discutida na a\u00e7\u00e3o inicial.<\/p>\n<p>\u201cH\u00e1, indiscutivelmente, constru\u00e7\u00e3o de linha de defesa distinta, inclusive quanto aos dispositivos legais, de modo que a mat\u00e9ria ora defendida na apela\u00e7\u00e3o n\u00e3o foi suscitada anteriormente no Ju\u00edzo de Primeiro Grau. N\u00e3o \u00e9 l\u00edcito \u00e0 parte inovar a tese inicial em quest\u00f5es n\u00e3o erigidas em primeiro grau de jurisdi\u00e7\u00e3o, o que enseja clara viola\u00e7\u00e3o aos princ\u00edpios do duplo grau de jurisdi\u00e7\u00e3o e contradit\u00f3rio e a ampla defesa, sendo, pois, inadmiss\u00edvel sua aprecia\u00e7\u00e3o em grau de recurso\u201d, afirmou o relator, Ant\u00f4nio Veloso Peleja J\u00fanior.<\/p>\n<p>O voto do magistrado foi seguido por unanimidade pelos demais desembargadores da Segunda C\u00e2mara de Direito P\u00fablico e Coletivo do Tribunal de Justi\u00e7a. Eles tamb\u00e9m votaram por aumentar o valor a ser pago pelo Estado em honor\u00e1rios advocat\u00edcios, de 10 para 11% sobre o valor da causa. Ainda cabe recurso.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Justi\u00e7a decidiu manter a prescri\u00e7\u00e3o de uma a\u00e7\u00e3o movida pelo Estado de<\/p>\n","protected":false},"author":0,"featured_media":91686,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-91685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=91685"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/91686"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=91685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=91685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=91685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}