{"id":91590,"date":"2022-09-26T11:08:20","date_gmt":"2022-09-26T14:08:20","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/26\/gazeta-dados-aponta-crescimento-de-mauro-que-tem-57-das-intencoes-de-votos-marcia-17-ritela-3-e-moises-1\/"},"modified":"2022-09-26T11:08:20","modified_gmt":"2022-09-26T14:08:20","slug":"gazeta-dados-aponta-crescimento-de-mauro-que-tem-57-das-intencoes-de-votos-marcia-17-ritela-3-e-moises-1","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/26\/gazeta-dados-aponta-crescimento-de-mauro-que-tem-57-das-intencoes-de-votos-marcia-17-ritela-3-e-moises-1\/","title":{"rendered":"Gazeta Dados aponta crescimento de Mauro que tem 57% das inten\u00e7\u00f5es de votos; Marcia 17%, Ritela 3% e Mois\u00e9s 1%"},"content":{"rendered":"<p>A segunda rodada de pesquisas do Instituto Gazeta Dados aponta que o governador Mauro Mendes (Uni\u00e3o) cresceu 19% nas inten\u00e7\u00f5es de voto, em rela\u00e7\u00e3o a pesquisa anterior, e agora tem 57% na modalidade estimulada e o instituto aponta que ele passou de 68% para 73,08% dos votos v\u00e1lidos. Marcia Pinheiro (PV)\u00a0 estava com 14% e agora tem 17% das inten\u00e7\u00f5es de votos que representam 21,79% dos votos v\u00e1lidos. O pastor Marcos Ritela (PTB) se manteve com 3%, ( 3,85% dos v\u00e1lidos) assim como Mois\u00e9s Franz (PSOL) representando 1,28% dos votos v\u00e1lidos. N\u00e3o responderam ou n\u00e3o sabem que estavam em 39% agora s\u00e3o\u00a0 16%.<\/p>\n<p>A margem de erro \u00e9 de 3 pontos percentuais para mais ou para menos, com um intervalo de confian\u00e7a de 95%. A pesquisa foi realizada entre 22 a 25 de setembro e ouviu 1080 pessoas de forma presencial e foi registrada na Justi\u00e7a Eleitoral sob o n\u00ba MT-01203\/2022. A metodologia da pesquisa \u00e9 Survey, com realiza\u00e7\u00e3o de entrevistas utilizando question\u00e1rio estruturado junto a uma amostra representativa populacional do Estado, abrangendo 46 munic\u00edpios das regi\u00f5es norte, nordeste, sudoeste, centro sul e sudeste.<\/p>\n<p>Na modalidade espont\u00e2nea, Mauro subiu de 25% para 43%, Marcia que antes tinha 6% foi para 10%, Ritela e Franz se mantiveram com 2% e 1% respectivamente. N\u00e3o responderam ou n\u00e3o sabem que antes somavam 66% agora s\u00e3o 44%<\/p>\n<p>Rejei\u00e7\u00e3o<br \/>\nMarcia 14%<br \/>\nMauro\u00a0 12%<br \/>\nRitela\u00a0 8% m<br \/>\nMois\u00e9s Franz 6%<br \/>\nNenhum deles\u00a015%<br \/>\nN\u00e3o sabem ou n\u00e3o responderam 45%.<\/p>\n<p>\u00a0<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A segunda rodada de pesquisas do Instituto Gazeta Dados aponta que o governador Mauro Mendes<\/p>\n","protected":false},"author":0,"featured_media":91591,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-91590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=91590"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/91591"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=91590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=91590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=91590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}