{"id":91586,"date":"2022-09-26T10:08:23","date_gmt":"2022-09-26T13:08:23","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/26\/semana-comeca-com-chuva-forte-em-grande-parte-do-pais\/"},"modified":"2022-09-26T10:08:23","modified_gmt":"2022-09-26T13:08:23","slug":"semana-comeca-com-chuva-forte-em-grande-parte-do-pais","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/26\/semana-comeca-com-chuva-forte-em-grande-parte-do-pais\/","title":{"rendered":"Semana come\u00e7a com chuva forte em grande parte do pa\u00eds"},"content":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A semana deve come\u00e7ar com muita chuva em parte do Centro-Sul do Brasil, especialmente nos estados de S\u00e3o Paulo, Paran\u00e1 e Mato Grosso do Sul.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>De acordo com a Climatempo, \u00e1reas de instabilidade nos n\u00edveis mais altos da atmosfera intensificam a forma\u00e7\u00e3o de nuvens carregadas.<\/p>\n<p>Nesta segunda-feira (26), a chuva pode vir acompanhada de trovoadas, fortes rajadas de vento e eventual queda de granizo, principalmente no interior paulista e no sul de Mato Grosso do Sul.<\/p>\n<p>Na cidade de S\u00e3o Paulo e regi\u00e3o metropolitana, a manh\u00e3 desta segunda deve ser marcada por muita nebulosidade e chuva fraca. \u00c0 tarde, por\u00e9m, aumentam os riscos de temporais, segundo a Climatempo. O CGE (Centro de Gerenciamento de Emerg\u00eancias), da Prefeitura de S\u00e3o Paulo, mant\u00e9m o alerta para alagamentos, e as temperaturas devem ficar entre 14\u00b0C e 19\u00b0C na capital.<\/p>\n<p>Na ter\u00e7a (27), as \u00e1reas de instabilidade continuam sobre o Centro-Sul do pa\u00eds, e a chegada de uma nova frente fria deve provocar chuva tamb\u00e9m nas demais regi\u00f5es do Paran\u00e1, no sul de Minas Gerais e em Santa Catarina, de acordo com a Climatempo.<\/p>\n<p>Em S\u00e3o Paulo o tempo tamb\u00e9m deve continuar inst\u00e1vel, com chuva j\u00e1 durante a manh\u00e3 em todo o estado, exceto nas cidades do norte. Na capital a previs\u00e3o \u00e9 de m\u00ednima de 15\u00b0C e m\u00e1xima de 21\u00b0C, segundo o CGE.<\/p>\n<p>A quarta-feira (28) deve ser o dia mais chuvoso da semana em todo o pa\u00eds. Conforme a frente fria se desloca pela costa do Sudeste, aumentam as condi\u00e7\u00f5es para chuva forte em S\u00e3o Paulo, Paran\u00e1, Mato Grosso do Sul, Rio de Janeiro e sul de Minas.<\/p>\n<p>No estado de S\u00e3o Paulo, a expectativa \u00e9 que a instabilidade persista pelo menos at\u00e9 sexta-feira (30). Com o grande volume de chuvas previsto, as autoridades alertam para o risco de transbordamento de rios e c\u00f3rregos e deslizamentos de terra.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Brasil<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/brasil\/1948352\/semana-comeca-com-chuva-forte-em-grande-parte-do-pais?utm_source=rss-brasil&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O PAULO, SP (FOLHAPRESS) &#8211; A semana deve come\u00e7ar com muita chuva em parte do<\/p>\n","protected":false},"author":0,"featured_media":91587,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-91586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=91586"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/91587"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=91586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=91586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=91586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}