{"id":91378,"date":"2022-09-23T19:08:53","date_gmt":"2022-09-23T22:08:53","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/23\/prefeitura-de-nova-mutum-planeja-obras-de-unidades-de-saude-mercado-do-bem-e-definira-empresa-que-fara-projetos\/"},"modified":"2022-09-23T19:08:53","modified_gmt":"2022-09-23T22:08:53","slug":"prefeitura-de-nova-mutum-planeja-obras-de-unidades-de-saude-mercado-do-bem-e-definira-empresa-que-fara-projetos","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/23\/prefeitura-de-nova-mutum-planeja-obras-de-unidades-de-saude-mercado-do-bem-e-definira-empresa-que-fara-projetos\/","title":{"rendered":"Prefeitura de Nova Mutum planeja obras de unidades de sa\u00fade, mercado do bem e definir\u00e1 empresa que far\u00e1 projetos"},"content":{"rendered":"<p>A secretaria de Planejamento e Assuntos Estrat\u00e9gicos de Nova Mutum publicou, no portal da transpar\u00eancia, que dever\u00e1 selecionar uma empresa no ramo de constru\u00e7\u00e3o civil para fazer os projetos de algumas obras. O certame ser\u00e1 disputado dia 30, na modalidade de tomada de pre\u00e7os.<\/p>\n<p>Uma equipe de engenheiros especializados formular\u00e1 o projeto para constru\u00e7\u00f5es como o mercado do bem, novas unidades b\u00e1sicas de sa\u00fade, centro social de Ranch\u00e3o (distrito), audit\u00f3rio municipal da prefeitura, setor administrativo e bloco de desenvolvimento no Parque Tecnol\u00f3gico, entre outras, planejadas para 2022, 2023 e 2024.<\/p>\n<p>Os projetos, baseados em obras de estrutura com concreto pr\u00e9-moldado, tamb\u00e9m ser\u00e3o complementados pelo memorial descritivo, memorial de c\u00e1lculo e relat\u00f3rio de materiais para a edifica\u00e7\u00e3o. Os trabalhos ser\u00e3o solicitados, conforme demanda da prefeitura.<\/p>\n<p>O contrato de atua\u00e7\u00e3o ter\u00e1 vig\u00eancia de 12 meses.\u00a0O investimento \u00e9 estimado em\u00a0R$ 245 mil.<\/p>\n<p>Fonte: S\u00f3 Not\u00edcias<br \/>\nArtigo Original em &gt; www.sonoticias.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A secretaria de Planejamento e Assuntos Estrat\u00e9gicos de Nova Mutum publicou, no portal da transpar\u00eancia,<\/p>\n","protected":false},"author":0,"featured_media":91379,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-91378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=91378"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/91379"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=91378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=91378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=91378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}