{"id":91340,"date":"2022-09-23T11:08:19","date_gmt":"2022-09-23T14:08:19","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2022\/09\/23\/bia-haddad-perde-de-russa-em-duelo-de-3h-e-cai-nas-quartas-em-toquio\/"},"modified":"2022-09-23T11:08:19","modified_gmt":"2022-09-23T14:08:19","slug":"bia-haddad-perde-de-russa-em-duelo-de-3h-e-cai-nas-quartas-em-toquio","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2022\/09\/23\/bia-haddad-perde-de-russa-em-duelo-de-3h-e-cai-nas-quartas-em-toquio\/","title":{"rendered":"Bia Haddad perde de russa em duelo de 3h e cai nas quartas em T\u00f3quio"},"content":{"rendered":"<p>Tenista n\u00famero 1 do Brasil, Beatriz Haddad Maia se despediu do Torneio de T\u00f3quio, de n\u00edvel WTA 500, nesta sexta-feira. Ela foi eliminada nas quartas de final pela russa Veronika Kudermetova, que tamb\u00e9m vive grande fase no circuito. A n\u00famero 13 do mundo venceu a 16\u00aa numa batalha de 3h14min por 2 sets a 1, com parciais de 6\/7 (4\/7), 7\/6 (8\/6) e 6\/1.<\/p>\n<p>Bia vinha de uma vit\u00f3ria por W.O. sobre a local Naomi Osaka, que alegou problemas f\u00edsicos para n\u00e3o entrar em quadra na quinta. Mesmo com um dia a mais de folga, a brasileira teve dificuldades diante de Kudermetova, tenista de 25 anos que vive seu auge no circuito. As duas precisaram de dois tie-breaks num confronto marcado pelo equil\u00edbrio nesta sexta.<\/p>\n<\/p>\n<p>A russa se destacou na postura mais agressiva em quadra. Ela disparou 45 bolas vencedoras, contra 22 da brasileira. Ao mesmo tempo, registrou mais erros n\u00e3o for\u00e7ados: 66 a 48. A estrat\u00e9gia deu certo e Kudermetova obteve seis quebras de servi\u00e7o ao longo da partida, contra tr\u00eas de Bia. <\/p>\n<\/p>\n<p>Apesar da derrota, Bia deve voltar ao 15\u00ba lugar do ranking, igualando sua melhor marca da carreira. Na corrida do ano, ela est\u00e1 em 14\u00ba, ainda sonhando com uma vaga no WTA Finals, o torneio que re\u00fane as oito melhores da temporada. Bia tenta disputar a prestigiada competi\u00e7\u00e3o pela primeira vez na carreira. <\/p>\n<\/p>\n<p>Agora Bia vai disputar, na sequ\u00eancia, o WTA 250 de Tallinn (Est\u00f4nia), o WTA 500 de Ostrava (Rep\u00fablica Checa), o WTA 500 de San Diego (EUA) e o WTA 1000 de Guadalajara (M\u00e9xico).<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1947624\/bia-haddad-perde-de-russa-em-duelo-de-3h-e-cai-nas-quartas-em-toquio?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tenista n\u00famero 1 do Brasil, Beatriz Haddad Maia se despediu do Torneio de T\u00f3quio, de<\/p>\n","protected":false},"author":0,"featured_media":91341,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-91340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=91340"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/91340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/91341"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=91340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=91340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=91340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}