{"id":794,"date":"2021-03-21T20:10:53","date_gmt":"2021-03-21T23:10:53","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/messi-brilha-em-goleada-e-se-torna-o-jogador-com-mais-partidas-pelo-barcelona\/"},"modified":"2021-03-21T20:10:53","modified_gmt":"2021-03-21T23:10:53","slug":"messi-brilha-em-goleada-e-se-torna-o-jogador-com-mais-partidas-pelo-barcelona","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/messi-brilha-em-goleada-e-se-torna-o-jogador-com-mais-partidas-pelo-barcelona\/","title":{"rendered":"Messi brilha em goleada e se torna o jogador com mais partidas pelo Barcelona"},"content":{"rendered":"<p>Lionel Messi teve mais um dia especial em sua vitoriosa carreira. Neste domingo, o meia argentino se tornou o atleta com mais partidas disputadas vestindo a camisa do Barcelona, superando o \u00eddolo espanhol Xavi Hern\u00e1ndez. No 768.\u00b0 jogo pelo time catal\u00e3o, atua\u00e7\u00e3o de gala, dois gols, assist\u00eancia e goleada sobre a Real Sociedad por 6 a 1, no est\u00e1dio Anoeta, em San Sebasti\u00e1n, pela 28.\u00aa rodada do Campeonato Espanhol.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>Messi j\u00e1 detinha outros recordes importantes pelo Barcelona que aumentaram no jogo disputado na regi\u00e3o do Pa\u00eds Basco. Maior artilheiro, ele agora soma 662 gols ao deixar a sua marca duas vezes. Tamb\u00e9m subiu no quesito assist\u00eancia. Agora s\u00e3o 270 passes para gols, ap\u00f3s servir Dest.<\/p>\n<p>O atacante franc\u00eas Antoine Griezmann abriu o caminho para a goleada em um duelo que costuma ser complicado para o Barcelona ap\u00f3s 37 minutos. Os catal\u00e3es n\u00e3o ganharam nem um ter\u00e7o das visitas \u00e0 Real Sociedad e at\u00e9 o primeiro gol o jogo era equilibrado. Mas mostraram inspira\u00e7\u00e3o em um domingo onde tudo deu certo.<\/p>\n<p>Dest fez o segundo e terceiro gols, um em assist\u00eancia de Messi, que ampliou para 4 a 0. O atacante franc\u00eas Demb\u00e9l\u00e9 deixou a sua marca antes de Barrenetxea anotar o de honra. O craque argentino fechou a conta no minuto final.<\/p>\n<p>A apresenta\u00e7\u00e3o de gala fez Messi ser escolhido o melhor do jogo diante da Real Sociedad. Merecidamente. Apesar de elimina\u00e7\u00e3o na Liga dos Campe\u00f5es da Europa, os comandados do t\u00e9cnico holand\u00eas Ronald Koeman vivem grande momento na temporada.<\/p>\n<p>O Barcelona chega a 13 jogos de invencibilidade no Campeonato Espanhol, com 12 vit\u00f3rias e um empate, seguindo forte na ca\u00e7a ao l\u00edder Atl\u00e9tico de Madrid. Agora s\u00e3o 62 pontos somados, na segunda coloca\u00e7\u00e3o, diante de 66 do rival. O Real Madrid est\u00e1 em terceiro com 60.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1788196\/messi-brilha-em-goleada-e-se-torna-o-jogador-com-mais-partidas-pelo-barcelona?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lionel Messi teve mais um dia especial em sua vitoriosa carreira. Neste domingo, o meia<\/p>\n","protected":false},"author":0,"featured_media":795,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=794"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/795"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}