{"id":788,"date":"2021-03-21T20:10:52","date_gmt":"2021-03-21T23:10:52","guid":{"rendered":"http:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/triatleta-de-40-anos-morre-de-covid-19-no-pr\/"},"modified":"2021-03-21T20:10:52","modified_gmt":"2021-03-21T23:10:52","slug":"triatleta-de-40-anos-morre-de-covid-19-no-pr","status":"publish","type":"post","link":"https:\/\/roteironoticias.com.br\/index.php\/2021\/03\/21\/triatleta-de-40-anos-morre-de-covid-19-no-pr\/","title":{"rendered":"Triatleta de 40 anos morre de Covid-19 no PR"},"content":{"rendered":"<p>O triatleta F\u00e1bio Torrecillas, 40, morreu neste s\u00e1bado (20) no Hospital Paran\u00e1, em Maring\u00e1, a 425 quil\u00f4metros de Curitiba. Ele passou dez dias intubado na UTI (Unidade de Terapia Intensiva) ap\u00f3s testar positivo para o novo coronav\u00edrus. O sepultamento aconteceu no in\u00edcio da tarde de hoje.<\/p>\n<div class=\"dummyPub\"><\/div>\n<p>De acordo com a fam\u00edlia, F\u00e1bio teve o diagn\u00f3stico confirmado para Covid-19 em 2 de mar\u00e7o. Em apenas cinco dias ap\u00f3s o teste, o triatleta teve 75% dos pulm\u00f5es comprometidos pela infec\u00e7\u00e3o e precisou de interna\u00e7\u00e3o. A intuba\u00e7\u00e3o ocorreu em 11 de mar\u00e7o.<\/p>\n<p>&#8220;Ele positivou em uma ter\u00e7a-feira e precisou ir ao m\u00e9dico no s\u00e1bado da mesma semana. Cinco dias depois foi para UTI ser intubado, indo a \u00f3bito ontem. O F\u00e1bio sentia muito cansa\u00e7o e na primeira tomografia j\u00e1 apontou 75% dos pulm\u00f5es tomados pela infec\u00e7\u00e3o&#8221;, disse o marido dele, o empres\u00e1rio Adilson Saldino Batista, 55. O casal estava junto h\u00e1 20 anos.<\/p>\n<p>F\u00e1bio era praticante do triatlo, esporte de alta intensidade que re\u00fane ciclismo, nata\u00e7\u00e3o e maratona.<\/p>\n<p>Participante das tr\u00eas \u00faltimas edi\u00e7\u00f5es do Ironman Brasil -o maior circuito de triatlo da Am\u00e9rica Latina-, o esportista se preparava para a Travessia do Leme ao Pontal, no Rio de Janeiro, com percurso de 34 quil\u00f4metros, no primeiro semestre deste ano. Em raz\u00e3o da pr\u00e1tica de atividade cardiorrespirat\u00f3ria, a agressividade da infec\u00e7\u00e3o surpreendeu os familiares.<\/p>\n<p>&#8220;Isso surpreendeu a gente porque era muito preparado, fazendo tr\u00eas vezes o Ironman, competindo em outras provas de nata\u00e7\u00e3o com mais de 20 quil\u00f4metros em mar aberto, al\u00e9m de ter feito mais de 1 mil quil\u00f4metro de ciclismo em competi\u00e7\u00f5es na It\u00e1lia. Ent\u00e3o isso deixa todo mundo boquiaberto. Estamos sem acreditar at\u00e9 agora&#8221;, comentou.<\/p>\n<p>O triatleta foi enterrado na cidade onde a fam\u00edlia mora, em Madaguari. A perda da luta contra a Covid-19 gerou como\u00e7\u00e3o de amigos e simpatizantes do esportista nas redes sociais.<\/p>\n<p>&#8220;Ele serviu de muita inspira\u00e7\u00e3o. Tem gente que, se hoje est\u00e1 nadando e pedalando na regi\u00e3o, \u00e9 por incentivo dele. O F\u00e1bio foi um exemplo de vida como pessoa e como atleta, buscando sempre superar os pr\u00f3prios limites&#8221;, concluiu o vi\u00favo, que pretende montar uma funda\u00e7\u00e3o esportiva como nome do triatleta para incentivar a pr\u00e1tica esportiva, em Maring\u00e1.<\/p>\n<p>Not\u00edcias ao Minuto Brasil &#8211; Esporte<br \/>\n<a href=\"https:\/\/www.noticiasaominuto.com.br\/esporte\/1788214\/triatleta-de-40-anos-morre-de-covid-19-no-pr?utm_source=rss-esporte&amp;amp;utm_medium=rss&amp;amp;utm_campaign=rssfeed\" target=\"_blank\" rel=\"noopener\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O triatleta F\u00e1bio Torrecillas, 40, morreu neste s\u00e1bado (20) no Hospital Paran\u00e1, em Maring\u00e1, a<\/p>\n","protected":false},"author":0,"featured_media":789,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=788"}],"version-history":[{"count":0,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/789"}],"wp:attachment":[{"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roteironoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}